{"id":79684,"date":"2022-10-10T14:24:49","date_gmt":"2022-10-10T13:24:49","guid":{"rendered":"https:\/\/rna.ao\/rna.ao\/?p=79684"},"modified":"2022-10-10T14:24:49","modified_gmt":"2022-10-10T13:24:49","slug":"lunda-norte-detido-cidadao-com-600-copias-de-bilhetes-de-identidade-falsos-que-preparou-para-legalizar-um-partido-politico","status":"publish","type":"post","link":"https:\/\/rna.ao\/rna.ao\/2022\/10\/10\/lunda-norte-detido-cidadao-com-600-copias-de-bilhetes-de-identidade-falsos-que-preparou-para-legalizar-um-partido-politico\/","title":{"rendered":"Lunda-Norte: Detido cidad\u00e3o com 600 c\u00f3pias de Bilhetes de Identidade falsos, que preparou para legalizar um Partido Pol\u00edtico"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"size-medium wp-image-74127 aligncenter\" src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2022\/08\/cela-770x402.jpg\" alt=\"\" width=\"770\" height=\"402\" srcset=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2022\/08\/cela-770x402.jpg 770w, https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2022\/08\/cela-1170x611.jpg 1170w, https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2022\/08\/cela-768x401.jpg 768w, https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2022\/08\/cela.jpg 1200w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/>Est\u00e1 detido, na Prov\u00edncia da Lunda-Norte, um cidad\u00e3o, suspeito de falsificar c\u00f3pias de Bilhetes de Identidade para a legaliza\u00e7\u00e3o de um Partido Pol\u00edtico. Em posse do suspeito, foram encontradas mais de seiscentas c\u00f3pias de Bilhetes de Identidade falsos. O Servi\u00e7o de Investiga\u00e7\u00e3o Criminal (SIC), na Lunda-Norte, acredita haver mais pessoas implicadas no processo. Saiba mais, no \u00e1udio abaixo, como rep\u00f3rter Clemente Babiquila:<\/p>\n\t<div class=\"qtmplayer-playlist-large\">\n\t\t<ul class=\"qtmplayer-playlist\">\n\t\t\t\n\t\t\t\t\t<li class=\"qtmplayer-trackitem\">\n\t\t<img src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2022\/08\/cela-100x100.jpg\" alt=\"cover\">\t\t<span \t\t\tdata-qtmplayer-cover=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2022\/08\/cela-370x370.jpg\"\n\t\t\t\t\t\tdata-qtmplayer-file=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2022\/10\/LUNDA-NORTE-SIC-13HRS.mp3-BOM.mp3\"\n\t\t\t\t\t\tdata-qtmplayer-title=\"Lunda-Norte: Detido cidad\u00e3o com 600 c\u00f3pias de Bilhetes de Identidade falsos, que preparou para legalizar um Partido Pol\u00edtico\"\n\t\t\t\t\t\tdata-qtmplayer-artist=\"RNA\"\n\t\t\t\t\t\tdata-qtmplayer-link=\"https:\/\/rna.ao\/rna.ao\/2022\/10\/10\/lunda-norte-detido-cidadao-com-600-copias-de-bilhetes-de-identidade-falsos-que-preparou-para-legalizar-um-partido-politico\/\"\n\t\t\t\t\t\tdata-qtmplayer-icon=\"file_download\"\n\t\t\t\t\t\tdata-qtmplayer-type=\"track\"\n\t\t\t class=\"qtmplayer-play qtmplayer-link-sec qtmplayer-play-btn\"><i class='material-icons'>play_arrow<\/i><\/span>\n\t\t<p>\n\t\t\t<span class=\"qtmplayer-tit\">Lunda-Norte: Detido cidad\u00e3o com 600 c\u00f3pias de Bilhetes de Identidade falsos, que preparou para legalizar um Partido Pol\u00edtico<\/span>\n\t\t\t<span class=\"qtmplayer-art\">RNA<\/span>\n\t\t<\/p>\n\t<\/li>\n\t\t<\/ul>\n\t<\/div>\t\t\t\n\t\n<p>Fonte: RNA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Est\u00e1 detido, na Prov\u00edncia da Lunda-Norte, um cidad\u00e3o, suspeito de falsificar c\u00f3pias de Bilhetes de Identidade para a legaliza\u00e7\u00e3o de um Partido Pol\u00edtico. Em posse do suspeito, foram encontradas mais de seiscentas c\u00f3pias de Bilhetes de Identidade falsos. O Servi\u00e7o de Investiga\u00e7\u00e3o Criminal (SIC), na Lunda-Norte, acredita haver mais pessoas ...<\/p>\n","protected":false},"author":8,"featured_media":74127,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[121,163],"tags":[],"_links":{"self":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/79684"}],"collection":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/comments?post=79684"}],"version-history":[{"count":1,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/79684\/revisions"}],"predecessor-version":[{"id":79689,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/79684\/revisions\/79689"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media\/74127"}],"wp:attachment":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media?parent=79684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/categories?post=79684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/tags?post=79684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}