{"id":76316,"date":"2022-09-12T08:25:43","date_gmt":"2022-09-12T07:25:43","guid":{"rendered":"https:\/\/rna.ao\/rna.ao\/?p=76316"},"modified":"2022-09-12T08:25:43","modified_gmt":"2022-09-12T07:25:43","slug":"por-atentado-a-saude-publica-aniesa-suspende-actividades-de-empresa-chinesa-que-operava-sem-licenca-ambiental-de-operacao","status":"publish","type":"post","link":"https:\/\/rna.ao\/rna.ao\/2022\/09\/12\/por-atentado-a-saude-publica-aniesa-suspende-actividades-de-empresa-chinesa-que-operava-sem-licenca-ambiental-de-operacao\/","title":{"rendered":"Por atentado \u00e0 sa\u00fade p\u00fablica, ANIESA suspende actividades de empresa chinesa que operava sem Licen\u00e7a Ambiental de Opera\u00e7\u00e3o"},"content":{"rendered":"<p><img loading=\"lazy\" class=\" wp-image-76319 aligncenter\" src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2022\/09\/Diogenes-de-Oliveira-ANIESA.jpg\" alt=\"\" width=\"801\" height=\"775\" \/>A ANIESA suspendeu as actividades de uma empresa chinesa, na capital do pa\u00eds, que exercia com\u00e9rcio ilegal, e por posse de elementos qu\u00edmicos para produ\u00e7\u00e3o de alcatr\u00e3o, sem a devida licen\u00e7a ambiental de opera\u00e7\u00f5es. A suspens\u00e3o dos servi\u00e7os desta empresa, s\u00f3 foi poss\u00edvel gra\u00e7as \u00e0 denuncia de um cidad\u00e3os, que acionou a ANIESA, por consentir que as infrac\u00e7\u00f5es constituem um atentado \u00e0 sa\u00fade p\u00fablica. Saiba mais, no \u00e1udio abaixo, com o rep\u00f3rter Daniel Marques:<\/p>\n\t<div class=\"qtmplayer-playlist-large\">\n\t\t<ul class=\"qtmplayer-playlist\">\n\t\t\t\n\t\t\t\t\t<li class=\"qtmplayer-trackitem\">\n\t\t<img src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2022\/09\/Diogenes-de-Oliveira-ANIESA-1-100x100.jpg\" alt=\"cover\">\t\t<span \t\t\tdata-qtmplayer-cover=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2022\/09\/Diogenes-de-Oliveira-ANIESA-1.jpg\"\n\t\t\t\t\t\tdata-qtmplayer-file=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2022\/09\/DANIEL-MARQUES-ANIESA-7HRS.mp3\"\n\t\t\t\t\t\tdata-qtmplayer-title=\"Por atentado \u00e0 sa\u00fade p\u00fablica, ANIESA suspende actividades de empresa chinesa que operava sem Licen\u00e7a Ambiental de Opera\u00e7\u00e3o\"\n\t\t\t\t\t\tdata-qtmplayer-artist=\"RNA\"\n\t\t\t\t\t\tdata-qtmplayer-link=\"https:\/\/rna.ao\/rna.ao\/2022\/09\/12\/por-atentado-a-saude-publica-aniesa-suspende-actividades-de-empresa-chinesa-que-operava-sem-licenca-ambiental-de-operacao\/\"\n\t\t\t\t\t\tdata-qtmplayer-icon=\"file_download\"\n\t\t\t\t\t\tdata-qtmplayer-type=\"track\"\n\t\t\t class=\"qtmplayer-play qtmplayer-link-sec qtmplayer-play-btn\"><i class='material-icons'>play_arrow<\/i><\/span>\n\t\t<p>\n\t\t\t<span class=\"qtmplayer-tit\">Por atentado \u00e0 sa\u00fade p\u00fablica, ANIESA suspende actividades de empresa chinesa que operava sem Licen\u00e7a Ambiental de Opera\u00e7\u00e3o<\/span>\n\t\t\t<span class=\"qtmplayer-art\">RNA<\/span>\n\t\t<\/p>\n\t<\/li>\n\t\t<\/ul>\n\t<\/div>\t\t\t\n\t\n<p>Fonte: RNA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A ANIESA suspendeu as actividades de uma empresa chinesa, na capital do pa\u00eds, que exercia com\u00e9rcio ilegal, e por posse de elementos qu\u00edmicos para produ\u00e7\u00e3o de alcatr\u00e3o, sem a devida licen\u00e7a ambiental de opera\u00e7\u00f5es. A suspens\u00e3o dos servi\u00e7os desta empresa, s\u00f3 foi poss\u00edvel gra\u00e7as \u00e0 denuncia de um cidad\u00e3os, que ...<\/p>\n","protected":false},"author":8,"featured_media":76320,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[121,141,133,163],"tags":[],"_links":{"self":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/76316"}],"collection":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/comments?post=76316"}],"version-history":[{"count":1,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/76316\/revisions"}],"predecessor-version":[{"id":76322,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/76316\/revisions\/76322"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media\/76320"}],"wp:attachment":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media?parent=76316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/categories?post=76316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/tags?post=76316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}