{"id":72236,"date":"2022-08-06T08:18:02","date_gmt":"2022-08-06T07:18:02","guid":{"rendered":"https:\/\/rna.ao\/rna.ao\/?p=72236"},"modified":"2022-08-06T08:18:02","modified_gmt":"2022-08-06T07:18:02","slug":"lider-do-mpla-apresenta-no-uige-agenda-de-governo-para-2022-2027","status":"publish","type":"post","link":"https:\/\/rna.ao\/rna.ao\/2022\/08\/06\/lider-do-mpla-apresenta-no-uige-agenda-de-governo-para-2022-2027\/","title":{"rendered":"L\u00edder do MPLA apresenta no U\u00edge Agenda de Governo para 2022\/2027"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"size-full wp-image-70664 alignleft\" src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2022\/07\/MPLA.jpg\" alt=\"\" width=\"324\" height=\"216\" \/>O candidato do MPLA \u00e0 Presidente da Rep\u00fablica, Jo\u00e3o Louren\u00e7o, est\u00e1 na Cidade do U\u00edge. Em terras do Bago Vermelho, Jo\u00e3o Louren\u00e7o e a coordena\u00e7\u00e3o eleitoral do \u201cpartido dos camaradas\u201d apresentam hoje, 06 de Agosto, ao eleitorado, naquela Prov\u00edncia, a Agenda de Governo do MPLA para os pr\u00f3ximos cinco anos. A Pra\u00e7a da Independ\u00eancia, na cidade do U\u00edge, \u00e9 o local escolhido para apresentar o documento. Clique, no \u00e1udio abaixo, e ou\u00e7a a reportagem do Manuel Esperan\u00e7a:<\/p>\n\t<div class=\"qtmplayer-playlist-large\">\n\t\t<ul class=\"qtmplayer-playlist\">\n\t\t\t\n\t\t\t\t\t<li class=\"qtmplayer-trackitem\">\n\t\t<img src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2022\/07\/JLO-MPLA-bom-100x100.jpg\" alt=\"cover\">\t\t<span \t\t\tdata-qtmplayer-cover=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2022\/07\/JLO-MPLA-bom.jpg\"\n\t\t\t\t\t\tdata-qtmplayer-file=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2022\/08\/MANUE-ESPERANCA.mp3\"\n\t\t\t\t\t\tdata-qtmplayer-title=\"L\u00edder do MPLA apresenta no U\u00edge Agenda de Governo para 2022\/2027\"\n\t\t\t\t\t\tdata-qtmplayer-artist=\"RNA\"\n\t\t\t\t\t\tdata-qtmplayer-link=\"https:\/\/rna.ao\/rna.ao\/2022\/08\/06\/lider-do-mpla-apresenta-no-uige-agenda-de-governo-para-2022-2027\/\"\n\t\t\t\t\t\tdata-qtmplayer-icon=\"file_download\"\n\t\t\t\t\t\tdata-qtmplayer-type=\"track\"\n\t\t\t class=\"qtmplayer-play qtmplayer-link-sec qtmplayer-play-btn\"><i class='material-icons'>play_arrow<\/i><\/span>\n\t\t<p>\n\t\t\t<span class=\"qtmplayer-tit\">L\u00edder do MPLA apresenta no U\u00edge Agenda de Governo para 2022\/2027<\/span>\n\t\t\t<span class=\"qtmplayer-art\">RNA<\/span>\n\t\t<\/p>\n\t<\/li>\n\t\t<\/ul>\n\t<\/div>\t\t\t\n\t\n<p>Fonte: RNA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O candidato do MPLA \u00e0 Presidente da Rep\u00fablica, Jo\u00e3o Louren\u00e7o, est\u00e1 na Cidade do U\u00edge. Em terras do Bago Vermelho, Jo\u00e3o Louren\u00e7o e a coordena\u00e7\u00e3o eleitoral do \u201cpartido dos camaradas\u201d apresentam hoje, 06 de Agosto, ao eleitorado, naquela Prov\u00edncia, a Agenda de Governo do MPLA para os pr\u00f3ximos cinco anos. ...<\/p>\n","protected":false},"author":8,"featured_media":71357,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[142,121,163],"tags":[],"_links":{"self":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/72236"}],"collection":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/comments?post=72236"}],"version-history":[{"count":1,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/72236\/revisions"}],"predecessor-version":[{"id":72238,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/72236\/revisions\/72238"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media\/71357"}],"wp:attachment":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media?parent=72236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/categories?post=72236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/tags?post=72236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}