{"id":72232,"date":"2022-08-06T03:09:09","date_gmt":"2022-08-06T02:09:09","guid":{"rendered":"https:\/\/rna.ao\/rna.ao\/?p=72232"},"modified":"2022-08-06T22:23:17","modified_gmt":"2022-08-06T21:23:17","slug":"central-de-zaporijia-atacada-ucrania-e-russia-culpam-se-mutuamente","status":"publish","type":"post","link":"https:\/\/rna.ao\/rna.ao\/2022\/08\/06\/central-de-zaporijia-atacada-ucrania-e-russia-culpam-se-mutuamente\/","title":{"rendered":"Central de Zapor\u00edjia atacada, Ucr\u00e2nia e R\u00fassia culpam-se mutuamente"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"size-full wp-image-72233 alignleft\" src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2022\/08\/download.jpeg\" alt=\"\" width=\"92\" height=\"92\" \/>Desde o in\u00edcio da guerra que o controlo de Zapor\u00edjia se apresenta como crucial para Ucr\u00e2nia e R\u00fassia e ao 163\u00ba. dia do conflito foi a luta pela maior central nuclear da Europa a dominar novamente as aten\u00e7\u00f5es, com acusa\u00e7\u00f5es de parte a parte e o perigo de um desastre nuclear.<\/p>\n<p>H\u00e1 muito que a central se encontra nas m\u00e3os dos russos, e esta sexta-feira a administra\u00e7\u00e3o militar local acusou as for\u00e7as ucranianas de terem danificado duas linhas de alta tens\u00e3o da central com um ataque.<\/p>\n<p>A resposta de Kiev n\u00e3o demorou, com a Energoatom, empresa estatal que gere a energia nuclear, a acusar os russos de terem atingido a central com tr\u00eas m\u00edsseis, arriscado a fuga de hidrog\u00e9nio e subst\u00e2ncias radiativas e provocando um elevado risco de inc\u00eandio. Ainda assim sublinharam que os reatores ainda estavam funcionais e que n\u00e3o tinha sido detetada nenhuma fuga.<\/p>\n<p>Bem longe do teatro de guerra, mais concretamente na cidade russa de Sochi, o Presidente russo, Vladimir Putin, recebeu o seu hom\u00f3logo turco, Recep Tayyip Erdo\u011fan.<\/p>\n<p>No menu, a coopera\u00e7\u00e3o bilateral entre os dois pa\u00edses, o acesso aos cereais da Ucr\u00e2nia e a crise na S\u00edria, mas de acordo com Kiev, Putin teria a inten\u00e7\u00e3o de discutir a compra de refinarias de petr\u00f3leo turcas por forma a contornar as san\u00e7\u00f5es de Europa e Estados Unidos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde o in\u00edcio da guerra que o controlo de Zapor\u00edjia se apresenta como crucial para Ucr\u00e2nia e R\u00fassia e ao 163\u00ba. dia do conflito foi a luta pela maior central nuclear da Europa a dominar novamente as aten\u00e7\u00f5es, com acusa\u00e7\u00f5es de parte a parte e o perigo de um desastre ...<\/p>\n","protected":false},"author":8,"featured_media":72233,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[143,137],"tags":[],"_links":{"self":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/72232"}],"collection":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/comments?post=72232"}],"version-history":[{"count":1,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/72232\/revisions"}],"predecessor-version":[{"id":72234,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/72232\/revisions\/72234"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media\/72233"}],"wp:attachment":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media?parent=72232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/categories?post=72232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/tags?post=72232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}