{"id":49132,"date":"2022-01-17T06:31:38","date_gmt":"2022-01-17T05:31:38","guid":{"rendered":"https:\/\/rna.ao\/rna.ao\/?p=49132"},"modified":"2022-01-17T07:51:59","modified_gmt":"2022-01-17T06:51:59","slug":"luanda-e-a-partir-de-hoje-capital-de-ministros-da-ciencia-tecnologia-e-ensino-superior","status":"publish","type":"post","link":"https:\/\/rna.ao\/rna.ao\/2022\/01\/17\/luanda-e-a-partir-de-hoje-capital-de-ministros-da-ciencia-tecnologia-e-ensino-superior\/","title":{"rendered":"Luanda \u00e9 a partir de hoje capital de Ministros da Ci\u00eancia, Tecnologia e Ensino Superior"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"size-full wp-image-45250 alignleft\" src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2021\/12\/CPLP.jpg\" alt=\"\" width=\"314\" height=\"177\" \/>A cidade de Luanda \u00e9, a partir desta segunda-feira, 17 de Janeiro, a capital da nona reuni\u00e3o de Ministros da Ci\u00eancia, Tecnologia e Ensino Superior, da Comunidade dos Pa\u00edses de L\u00edngua Portuguesa (CPLP).<\/p>\n<p>Em nota de imprensa, o Minist\u00e9rio do Ensino Superior, Ci\u00eancia, Tecnologia e Inova\u00e7\u00e3o de Angola, indica que o evento da CPLP vai avaliar o grau de implementa\u00e7\u00e3o do Plano Estrat\u00e9gico de Coopera\u00e7\u00e3o Multilateral, para o per\u00edodo 2014 e 2020, bem como aprovar uma nova agenda pol\u00edtica, para at\u00e9 2026.<\/p>\n<p>Fonte: RNA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A cidade de Luanda \u00e9, a partir desta segunda-feira, 17 de Janeiro, a capital da nona reuni\u00e3o de Ministros da Ci\u00eancia, Tecnologia e Ensino Superior, da Comunidade dos Pa\u00edses de L\u00edngua Portuguesa (CPLP). Em nota de imprensa, o Minist\u00e9rio do Ensino Superior, Ci\u00eancia, Tecnologia e Inova\u00e7\u00e3o de Angola, indica que ...<\/p>\n","protected":false},"author":8,"featured_media":45250,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[142,121,163],"tags":[],"_links":{"self":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/49132"}],"collection":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/comments?post=49132"}],"version-history":[{"count":2,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/49132\/revisions"}],"predecessor-version":[{"id":49192,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/49132\/revisions\/49192"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media\/45250"}],"wp:attachment":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media?parent=49132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/categories?post=49132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/tags?post=49132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}