{"id":218044,"date":"2026-05-13T20:37:56","date_gmt":"2026-05-13T19:37:56","guid":{"rendered":"https:\/\/rna.ao\/rna.ao\/?p=218044"},"modified":"2026-05-13T20:37:56","modified_gmt":"2026-05-13T19:37:56","slug":"actriz-lesliana-pereira-representa-angola-nos-maiores-premios-do-audiovisual-africano","status":"publish","type":"post","link":"https:\/\/rna.ao\/rna.ao\/2026\/05\/13\/actriz-lesliana-pereira-representa-angola-nos-maiores-premios-do-audiovisual-africano\/","title":{"rendered":"Actriz Lesliana Pereira representa Angola nos maiores pr\u00e9mios do audiovisual africano"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignnone size-medium wp-image-218045\" src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2026\/05\/0754122c-fc3a-4f14-be24-50b402ecadb3-616x770.jpeg\" alt=\"\" width=\"616\" height=\"770\" srcset=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2026\/05\/0754122c-fc3a-4f14-be24-50b402ecadb3-616x770.jpeg 616w, https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2026\/05\/0754122c-fc3a-4f14-be24-50b402ecadb3-936x1170.jpeg 936w, https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2026\/05\/0754122c-fc3a-4f14-be24-50b402ecadb3-768x960.jpeg 768w, https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2026\/05\/0754122c-fc3a-4f14-be24-50b402ecadb3-1229x1536.jpeg 1229w, https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2026\/05\/0754122c-fc3a-4f14-be24-50b402ecadb3.jpeg 1280w\" sizes=\"(max-width: 616px) 100vw, 616px\" \/><br \/>\nA actriz angolana Lesliana Pereira participou, em Lagos, na 12.\u00aa edi\u00e7\u00e3o dos Africa Magic Viewers\u2019 Choice Awards 2026 (AMVCA 12), um dos maiores eventos dedicados ao cinema e televis\u00e3o africanos.<\/p>\n<p>A presen\u00e7a da artista angolana no certame serviu para promover o talento nacional e refor\u00e7ar a projec\u00e7\u00e3o da cultura angolana no panorama audiovisual africano.<\/p>\n<p>Segundo Lesliana Pereira, a participa\u00e7\u00e3o no evento representa a afirma\u00e7\u00e3o de Angola nas ind\u00fastrias criativas do continente e contribui para a valoriza\u00e7\u00e3o da imagem do pa\u00eds al\u00e9m-fronteiras.<\/p>\n<p>O evento reuniu v\u00e1rias figuras do cinema africano e da ind\u00fastria cinematogr\u00e1fica nigeriana, Nollywood, considerada uma das mais influentes do continente.<\/p>\n<p>Entretanto, o Instituto da Ind\u00fastria Criativa da Nig\u00e9ria manifestou interesse em refor\u00e7ar a coopera\u00e7\u00e3o com Angola no sector audiovisual, incluindo a forma\u00e7\u00e3o de actores angolanos e produ\u00e7\u00e3o conjunta de longas-metragens.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A actriz angolana Lesliana Pereira participou, em Lagos, na 12.\u00aa edi\u00e7\u00e3o dos Africa Magic Viewers\u2019 Choice Awards 2026 (AMVCA 12), um dos maiores eventos dedicados ao cinema e televis\u00e3o africanos. A presen\u00e7a da artista angolana no certame serviu para promover o talento nacional e refor\u00e7ar a projec\u00e7\u00e3o da cultura angolana ...<\/p>\n","protected":false},"author":9,"featured_media":218046,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[142,121,163],"tags":[],"_links":{"self":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/218044"}],"collection":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/comments?post=218044"}],"version-history":[{"count":1,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/218044\/revisions"}],"predecessor-version":[{"id":218047,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/218044\/revisions\/218047"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media\/218046"}],"wp:attachment":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media?parent=218044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/categories?post=218044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/tags?post=218044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}