{"id":211078,"date":"2026-03-19T13:43:56","date_gmt":"2026-03-19T12:43:56","guid":{"rendered":"https:\/\/rna.ao\/rna.ao\/?p=211078"},"modified":"2026-03-19T13:47:44","modified_gmt":"2026-03-19T12:47:44","slug":"tribunal-de-comarca-de-luanda-ordena-restituicao-do-centro-comercial-nova-era-ao-general-helder-vieira-dias-kopelipa","status":"publish","type":"post","link":"https:\/\/rna.ao\/rna.ao\/2026\/03\/19\/tribunal-de-comarca-de-luanda-ordena-restituicao-do-centro-comercial-nova-era-ao-general-helder-vieira-dias-kopelipa\/","title":{"rendered":"Tribunal de Comarca de Luanda ordena restitui\u00e7\u00e3o  do espa\u00e7o onde est\u00e1 localizado o Centro Comercial NOVA ERA em Cacuaco ao General Kopelipa"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignnone wp-image-123226\" src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2023\/11\/General-Kopelipa.jpg\" alt=\"\" width=\"425\" height=\"284\" \/><\/p>\n<p>O Tribunal de Comarca de Luanda, ordenou atrav\u00e9s de uma providencia cautelar, a restitui\u00e7\u00e3o do espa\u00e7o onde est\u00e1 localizado o Centro Comercial NOVA ERA, no munic\u00edpio de cacuaco, ao general H\u00e9lder Vieira Dias J\u00fanior Kopelipa, como propriet\u00e1rio leg\u00edtimo.<br \/>\nO facto, est\u00e1 a gerar\u00a0 preocupa\u00e7\u00e3o no seio dos jovens que trabalham naquele Centro Comercial\u00a0 e que\u00a0 temem o desemprego. Jornalista Jane Ferreira. Clique no a\u00fadio abaixo e ou\u00e7a:<\/p>\n\t<div class=\"qtmplayer-playlist-large\">\n\t\t<ul class=\"qtmplayer-playlist\">\n\t\t\t\n\t\t\t\t\t<li class=\"qtmplayer-trackitem\">\n\t\t<img src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2023\/11\/General-Kopelipa-100x100.jpg\" alt=\"cover\">\t\t<span \t\t\tdata-qtmplayer-cover=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2023\/11\/General-Kopelipa.jpg\"\n\t\t\t\t\t\tdata-qtmplayer-file=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2026\/03\/JANE-FERREIRA-NOVA-ERA-13HRS-1.mp3\"\n\t\t\t\t\t\tdata-qtmplayer-title=\"Tribunal de Comarca de Luanda ordena restitui\u00e7\u00e3o  do espa\u00e7o onde est\u00e1 localizado o Centro Comercial NOVA ERA em Cacuaco ao General Kopelipa\"\n\t\t\t\t\t\tdata-qtmplayer-artist=\"Patr\u00edcia Campos\"\n\t\t\t\t\t\tdata-qtmplayer-link=\"https:\/\/rna.ao\/rna.ao\/2026\/03\/19\/tribunal-de-comarca-de-luanda-ordena-restituicao-do-centro-comercial-nova-era-ao-general-helder-vieira-dias-kopelipa\/\"\n\t\t\t\t\t\tdata-qtmplayer-icon=\"file_download\"\n\t\t\t\t\t\tdata-qtmplayer-type=\"track\"\n\t\t\t class=\"qtmplayer-play qtmplayer-link-sec qtmplayer-play-btn\"><i class='material-icons'>play_arrow<\/i><\/span>\n\t\t<p>\n\t\t\t<span class=\"qtmplayer-tit\">Tribunal de Comarca de Luanda ordena restitui\u00e7\u00e3o  do espa\u00e7o onde est\u00e1 localizado o Centro Comercial NOVA ERA em Cacuaco ao General Kopelipa<\/span>\n\t\t\t<span class=\"qtmplayer-art\">Patr\u00edcia Campos<\/span>\n\t\t<\/p>\n\t<\/li>\n\t\t<\/ul>\n\t<\/div>\t\t\t\n\t\n<p>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Tribunal de Comarca de Luanda, ordenou atrav\u00e9s de uma providencia cautelar, a restitui\u00e7\u00e3o do espa\u00e7o onde est\u00e1 localizado o Centro Comercial NOVA ERA, no munic\u00edpio de cacuaco, ao general H\u00e9lder Vieira Dias J\u00fanior Kopelipa, como propriet\u00e1rio leg\u00edtimo. O facto, est\u00e1 a gerar\u00a0 preocupa\u00e7\u00e3o no seio dos jovens que trabalham ...<\/p>\n","protected":false},"author":21,"featured_media":123226,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[142,121,164,163,1],"tags":[],"_links":{"self":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/211078"}],"collection":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/comments?post=211078"}],"version-history":[{"count":4,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/211078\/revisions"}],"predecessor-version":[{"id":211088,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/211078\/revisions\/211088"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media\/123226"}],"wp:attachment":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media?parent=211078"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/categories?post=211078"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/tags?post=211078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}