{"id":209062,"date":"2026-02-28T09:54:29","date_gmt":"2026-02-28T08:54:29","guid":{"rendered":"https:\/\/rna.ao\/rna.ao\/?p=209062"},"modified":"2026-02-28T09:54:29","modified_gmt":"2026-02-28T08:54:29","slug":"eua-e-israel-lancam-ofensiva-contra-irao","status":"publish","type":"post","link":"https:\/\/rna.ao\/rna.ao\/2026\/02\/28\/eua-e-israel-lancam-ofensiva-contra-irao\/","title":{"rendered":"EUA e Israel lan\u00e7am ofensiva contra Ir\u00e3o"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"size-medium wp-image-209064\" src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2026\/02\/IMG_0071-770x488.jpeg\" alt=\"\" width=\"770\" height=\"488\" srcset=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2026\/02\/IMG_0071-770x488.jpeg 770w, https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2026\/02\/IMG_0071-768x487.jpeg 768w, https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2026\/02\/IMG_0071.jpeg 1046w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/><\/p>\n<p>Israel lan\u00e7ou, na \u00faltima noite, um ataque a\u00e9reo contra a capital do Ir\u00e3o, provocando nuvens de fumo no norte e no centro. As explos\u00f5es ocorreram numa zona aparentemente pr\u00f3xima dos escrit\u00f3rios do l\u00edder supremo iraniano, o aiatola Ali Khamenei.<\/p>\n<p>A ofensiva foi confirmada pelo ex-Presidente dos Estados Unidos da Am\u00e9rica, Donald Trump, que reconheceu publicamente a opera\u00e7\u00e3o israelita, sem avan\u00e7ar detalhes adicionais sobre o seu alcance ou objectivos estrat\u00e9gicos.<\/p>\n<p>At\u00e9 ao momento, as autoridades iranianas n\u00e3o divulgaram um balan\u00e7o oficial de v\u00edtimas ou danos, enquanto a comunidade internacional acompanha com preocupa\u00e7\u00e3o o agravamento das tens\u00f5es entre Israel e o Ir\u00e3o, num contexto j\u00e1 marcado por instabilidade na regi\u00e3o do M\u00e9dio Oriente<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Israel lan\u00e7ou, na \u00faltima noite, um ataque a\u00e9reo contra a capital do Ir\u00e3o, provocando nuvens de fumo no norte e no centro. As explos\u00f5es ocorreram numa zona aparentemente pr\u00f3xima dos escrit\u00f3rios do l\u00edder supremo iraniano, o aiatola Ali Khamenei. A ofensiva foi confirmada pelo ex-Presidente dos Estados Unidos da Am\u00e9rica, ...<\/p>\n","protected":false},"author":9,"featured_media":209064,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[142,121,163,1],"tags":[],"_links":{"self":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/209062"}],"collection":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/comments?post=209062"}],"version-history":[{"count":1,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/209062\/revisions"}],"predecessor-version":[{"id":209065,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/209062\/revisions\/209065"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media\/209064"}],"wp:attachment":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media?parent=209062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/categories?post=209062"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/tags?post=209062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}