{"id":207876,"date":"2026-02-13T10:19:12","date_gmt":"2026-02-13T09:19:12","guid":{"rendered":"https:\/\/rna.ao\/rna.ao\/?p=207876"},"modified":"2026-02-13T10:19:33","modified_gmt":"2026-02-13T09:19:33","slug":"ong-regista-perto-de-sete-mil-mortos-durante-protestos-no-irao","status":"publish","type":"post","link":"https:\/\/rna.ao\/rna.ao\/2026\/02\/13\/ong-regista-perto-de-sete-mil-mortos-durante-protestos-no-irao\/","title":{"rendered":"ONG regista perto de sete mil mortos durante protestos no Ir\u00e3o"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"size-full wp-image-190968 alignleft\" src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/09\/irao.jpg\" alt=\"\" width=\"275\" height=\"183\" \/>Sete mil pessoas morreram durante a repress\u00e3o dos protestos antigovernamentais em janeiro no Ir\u00e3o e muitas outras est\u00e3o desaparecidas, segundo a Ag\u00eancia de Not\u00edcias de Activistas de Direitos Humanos, citada hoje pela ag\u00eancia Associated Press.<\/p>\n<p>A organiza\u00e7\u00e3o n\u00e3o-governamental, sediada nos Estados Unidos, tem sido precisa na contagem de mortes durante outras vagas de protestos no Ir\u00e3o e conta com uma rede de activistas no pa\u00eds para verificar as mortes, segundo a AP, que n\u00e3o consegue, por\u00e9m, confirmar os dados de forma independente, dado que as autoridades de Teer\u00e3o interromperam o acesso \u00e0 Internet e as chamadas internacionais.<\/p>\n<p>No seguimento da revolta popular contra a teocracia iraniana, o Presidente norte-americano, Donald Trump, amea\u00e7ou atacar o Ir\u00e3o, enquanto enviava uma frota naval para a regi\u00e3o e posteriormente, exigiu um acordo sobre o programa nuclear do Ir\u00e3o, que aceitou reatar o di\u00e1logo com Washington, num primeiro encontro das duas partes realizado em Om\u00e3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sete mil pessoas morreram durante a repress\u00e3o dos protestos antigovernamentais em janeiro no Ir\u00e3o e muitas outras est\u00e3o desaparecidas, segundo a Ag\u00eancia de Not\u00edcias de Activistas de Direitos Humanos, citada hoje pela ag\u00eancia Associated Press. A organiza\u00e7\u00e3o n\u00e3o-governamental, sediada nos Estados Unidos, tem sido precisa na contagem de mortes durante ...<\/p>\n","protected":false},"author":23,"featured_media":190968,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[143,137,1],"tags":[],"_links":{"self":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/207876"}],"collection":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/comments?post=207876"}],"version-history":[{"count":1,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/207876\/revisions"}],"predecessor-version":[{"id":207877,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/207876\/revisions\/207877"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media\/190968"}],"wp:attachment":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media?parent=207876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/categories?post=207876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/tags?post=207876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}