{"id":205585,"date":"2026-01-23T13:20:27","date_gmt":"2026-01-23T12:20:27","guid":{"rendered":"https:\/\/rna.ao\/rna.ao\/?p=205585"},"modified":"2026-01-23T13:21:28","modified_gmt":"2026-01-23T12:21:28","slug":"instituto-nacional-de-estatistica-da-inicio-a-apresentacao-dos-perfis-socio-demograficos-das-21-provincias-do-pais","status":"publish","type":"post","link":"https:\/\/rna.ao\/rna.ao\/2026\/01\/23\/instituto-nacional-de-estatistica-da-inicio-a-apresentacao-dos-perfis-socio-demograficos-das-21-provincias-do-pais\/","title":{"rendered":"Instituto Nacional de Estat\u00edstica d\u00e1 in\u00edcio \u00e0 apresenta\u00e7\u00e3o dos perfis s\u00f3cio-demogr\u00e1ficos das 21 prov\u00edncias do pa\u00eds"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignnone size-medium wp-image-205586\" src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2026\/01\/IMG_4923-770x513.jpeg\" alt=\"\" width=\"770\" height=\"513\" srcset=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2026\/01\/IMG_4923-770x513.jpeg 770w, https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2026\/01\/IMG_4923-1170x779.jpeg 1170w, https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2026\/01\/IMG_4923-768x512.jpeg 768w, https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2026\/01\/IMG_4923-1536x1023.jpeg 1536w, https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2026\/01\/IMG_4923.jpeg 2048w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/>Neste ano, o Instituto Nacional de Estat\u00edstica &#8211; INE est\u00e1 a trabalhar na elabora\u00e7\u00e3o dos perfis das 21 prov\u00edncias do pa\u00eds, sustentados pelos resultados locais constantes no Censo Geral de 2024.<\/p>\n<p>Nesta altura, dez das 21 prov\u00edncias de Angola j\u00e1 t\u00eam os seus perfis elaborados, seguindo-se agora a fase da apresenta\u00e7\u00e3o p\u00fablica dos relat\u00f3rios s\u00f3cio-demogr\u00e1ficos.<\/p>\n<p>O chefe de Departamento de Censo e Inqu\u00e9ritos Especiais do INE, Ezequiel Lu\u00eds, avan\u00e7ou que, a partir do dia 28 deste m\u00eas, arranca o processo de apresenta\u00e7\u00e3o dos perfis s\u00f3cio-demogr\u00e1ficos, que decorrer\u00e1 at\u00e9 ao dia 24 de Fevereiro.<\/p>\n<p>Segundo o respons\u00e1vel, esta primeira fase do processo ter\u00e1 in\u00edcio no Sul de Angola. Clique no \u00e1udio e ou\u00e7a:<\/p>\n\t<div class=\"qtmplayer-playlist-large\">\n\t\t<ul class=\"qtmplayer-playlist\">\n\t\t\t\n\t\t\t\t\t<li class=\"qtmplayer-trackitem\">\n\t\t<img src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2026\/01\/IMG_4923-100x100.jpeg\" alt=\"cover\">\t\t<span \t\t\tdata-qtmplayer-cover=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2026\/01\/IMG_4923-370x370.jpeg\"\n\t\t\t\t\t\tdata-qtmplayer-file=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2026\/01\/EZEQUIEL-LUIS-1-13-HRS.mp3\"\n\t\t\t\t\t\tdata-qtmplayer-title=\"Instituto Nacional de Estat\u00edstica d\u00e1 in\u00edcio \u00e0 apresenta\u00e7\u00e3o dos perfis s\u00f3cio-demogr\u00e1ficos das 21 prov\u00edncias do pa\u00eds\"\n\t\t\t\t\t\tdata-qtmplayer-artist=\"Juliana Nunes\"\n\t\t\t\t\t\tdata-qtmplayer-link=\"https:\/\/rna.ao\/rna.ao\/2026\/01\/23\/instituto-nacional-de-estatistica-da-inicio-a-apresentacao-dos-perfis-socio-demograficos-das-21-provincias-do-pais\/\"\n\t\t\t\t\t\tdata-qtmplayer-icon=\"file_download\"\n\t\t\t\t\t\tdata-qtmplayer-type=\"track\"\n\t\t\t class=\"qtmplayer-play qtmplayer-link-sec qtmplayer-play-btn\"><i class='material-icons'>play_arrow<\/i><\/span>\n\t\t<p>\n\t\t\t<span class=\"qtmplayer-tit\">Instituto Nacional de Estat\u00edstica d\u00e1 in\u00edcio \u00e0 apresenta\u00e7\u00e3o dos perfis s\u00f3cio-demogr\u00e1ficos das 21 prov\u00edncias do pa\u00eds<\/span>\n\t\t\t<span class=\"qtmplayer-art\">Juliana Nunes<\/span>\n\t\t<\/p>\n\t<\/li>\n\t\t<\/ul>\n\t<\/div>\t\t\t\n\t\n<p>Ezequiel Lu\u00eds trouxe \u00e0 mem\u00f3ria colectiva os resultados definitivos sobre o n\u00famero real da popula\u00e7\u00e3o angolana, que \u00e9 de 36.604.681 habitantes, ou seja, uma popula\u00e7\u00e3o acima dos 36 milh\u00f5es de pessoas. Clique no \u00e1udio e ou\u00e7a:<\/p>\n\t<div class=\"qtmplayer-playlist-large\">\n\t\t<ul class=\"qtmplayer-playlist\">\n\t\t\t\n\t\t\t\t\t<li class=\"qtmplayer-trackitem\">\n\t\t<img src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2026\/01\/IMG_4923-100x100.jpeg\" alt=\"cover\">\t\t<span \t\t\tdata-qtmplayer-cover=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2026\/01\/IMG_4923-370x370.jpeg\"\n\t\t\t\t\t\tdata-qtmplayer-file=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2026\/01\/EZEQUIEL-LUIS-2-13-HRS.mp3\"\n\t\t\t\t\t\tdata-qtmplayer-title=\"Instituto Nacional de Estat\u00edstica d\u00e1 in\u00edcio \u00e0 apresenta\u00e7\u00e3o dos perfis s\u00f3cio-demogr\u00e1ficos das 21 prov\u00edncias do pa\u00eds\"\n\t\t\t\t\t\tdata-qtmplayer-artist=\"Juliana Nunes\"\n\t\t\t\t\t\tdata-qtmplayer-link=\"https:\/\/rna.ao\/rna.ao\/2026\/01\/23\/instituto-nacional-de-estatistica-da-inicio-a-apresentacao-dos-perfis-socio-demograficos-das-21-provincias-do-pais\/\"\n\t\t\t\t\t\tdata-qtmplayer-icon=\"file_download\"\n\t\t\t\t\t\tdata-qtmplayer-type=\"track\"\n\t\t\t class=\"qtmplayer-play qtmplayer-link-sec qtmplayer-play-btn\"><i class='material-icons'>play_arrow<\/i><\/span>\n\t\t<p>\n\t\t\t<span class=\"qtmplayer-tit\">Instituto Nacional de Estat\u00edstica d\u00e1 in\u00edcio \u00e0 apresenta\u00e7\u00e3o dos perfis s\u00f3cio-demogr\u00e1ficos das 21 prov\u00edncias do pa\u00eds<\/span>\n\t\t\t<span class=\"qtmplayer-art\">Juliana Nunes<\/span>\n\t\t<\/p>\n\t<\/li>\n\t\t<\/ul>\n\t<\/div>\t\t\t\n\t\n<p>O respons\u00e1vel avan\u00e7ou ainda que o Censo Geral de 2024 mostra um aumento significativo da popula\u00e7\u00e3o angolana com documentos de cidadania, nomeadamente Bilhete de Identidade e C\u00e9dula de Registo Civil, em compara\u00e7\u00e3o com o censo anterior. Clique no \u00e1udio e ou\u00e7a:<\/p>\n\t<div class=\"qtmplayer-playlist-large\">\n\t\t<ul class=\"qtmplayer-playlist\">\n\t\t\t\n\t\t\t\t\t<li class=\"qtmplayer-trackitem\">\n\t\t<img src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2026\/01\/IMG_4923-100x100.jpeg\" alt=\"cover\">\t\t<span \t\t\tdata-qtmplayer-cover=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2026\/01\/IMG_4923-370x370.jpeg\"\n\t\t\t\t\t\tdata-qtmplayer-file=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2026\/01\/EZEQUIEL-LUIS-3-13-HRS.mp3\"\n\t\t\t\t\t\tdata-qtmplayer-title=\"Instituto Nacional de Estat\u00edstica d\u00e1 in\u00edcio \u00e0 apresenta\u00e7\u00e3o dos perfis s\u00f3cio-demogr\u00e1ficos das 21 prov\u00edncias do pa\u00eds\"\n\t\t\t\t\t\tdata-qtmplayer-artist=\"Juliana Nunes\"\n\t\t\t\t\t\tdata-qtmplayer-link=\"https:\/\/rna.ao\/rna.ao\/2026\/01\/23\/instituto-nacional-de-estatistica-da-inicio-a-apresentacao-dos-perfis-socio-demograficos-das-21-provincias-do-pais\/\"\n\t\t\t\t\t\tdata-qtmplayer-icon=\"file_download\"\n\t\t\t\t\t\tdata-qtmplayer-type=\"track\"\n\t\t\t class=\"qtmplayer-play qtmplayer-link-sec qtmplayer-play-btn\"><i class='material-icons'>play_arrow<\/i><\/span>\n\t\t<p>\n\t\t\t<span class=\"qtmplayer-tit\">Instituto Nacional de Estat\u00edstica d\u00e1 in\u00edcio \u00e0 apresenta\u00e7\u00e3o dos perfis s\u00f3cio-demogr\u00e1ficos das 21 prov\u00edncias do pa\u00eds<\/span>\n\t\t\t<span class=\"qtmplayer-art\">Juliana Nunes<\/span>\n\t\t<\/p>\n\t<\/li>\n\t\t<\/ul>\n\t<\/div>\t\t\t\n\t\n","protected":false},"excerpt":{"rendered":"<p>Neste ano, o Instituto Nacional de Estat\u00edstica &#8211; INE est\u00e1 a trabalhar na elabora\u00e7\u00e3o dos perfis das 21 prov\u00edncias do pa\u00eds, sustentados pelos resultados locais constantes no Censo Geral de 2024. Nesta altura, dez das 21 prov\u00edncias de Angola j\u00e1 t\u00eam os seus perfis elaborados, seguindo-se agora a fase da ...<\/p>\n","protected":false},"author":16,"featured_media":205586,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[142,121,164,163],"tags":[],"_links":{"self":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/205585"}],"collection":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/comments?post=205585"}],"version-history":[{"count":2,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/205585\/revisions"}],"predecessor-version":[{"id":205591,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/205585\/revisions\/205591"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media\/205586"}],"wp:attachment":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media?parent=205585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/categories?post=205585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/tags?post=205585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}