{"id":188428,"date":"2025-08-09T10:02:18","date_gmt":"2025-08-09T09:02:18","guid":{"rendered":"https:\/\/rna.ao\/rna.ao\/?p=188428"},"modified":"2025-08-09T10:02:18","modified_gmt":"2025-08-09T09:02:18","slug":"grande-parte-do-burundi-esta-sem-eletricidade-ha-quase-cinco-dias","status":"publish","type":"post","link":"https:\/\/rna.ao\/rna.ao\/2025\/08\/09\/grande-parte-do-burundi-esta-sem-eletricidade-ha-quase-cinco-dias\/","title":{"rendered":"Grande parte do Burundi est\u00e1 sem eletricidade h\u00e1 quase cinco dias"},"content":{"rendered":"<div class=\"mx-3 mx-md-5 article-text margin-top-30\">\n<p><img loading=\"lazy\" class=\"alignnone size-medium wp-image-188429\" src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/08\/IMG_4652-770x578.jpeg\" alt=\"\" width=\"770\" height=\"578\" srcset=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/08\/IMG_4652-770x578.jpeg 770w, https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/08\/IMG_4652-1170x878.jpeg 1170w, https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/08\/IMG_4652-768x576.jpeg 768w, https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/08\/IMG_4652-1536x1152.jpeg 1536w, https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/08\/IMG_4652.jpeg 1600w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/><\/p>\n<p class=\"article-lead readthis-1675143\">Grande parte do Burundi vive desde segunda-feira sem eletricidade ou quase, com a capital Bujumbura paralisada, no momento em que o pa\u00eds enfrenta tamb\u00e9m uma grave escassez de combust\u00edveis.<\/p>\n<\/div>\n<div class=\"hidden-content relative\">\n<div class=\"mx-3 mx-md-5 article-text\">\n<div class=\"article-body readthis-1675143\">\n<p>Os cortes de energia, programados desde segunda-feira e que devem durar at\u00e9 14 de agosto, s\u00e3o devidos a &#8220;trabalhos de liga\u00e7\u00e3o&#8221; na rede burundiana, anunciou a Regideso, a empresa p\u00fablica de produ\u00e7\u00e3o e distribui\u00e7\u00e3o de eletricidade e \u00e1gua.<\/p>\n<p>Quatro das cinco prov\u00edncias do Burundi foram afetadas e a capital est\u00e1 paralisada, com alguns bairros a viver h\u00e1 cinco dias sem eletricidade, \u00e1gua ou acesso \u00e0 Internet, segundo diversos testemunhos.<\/p>\n<p>V\u00e1rios bancos anunciaram nas redes sociais que n\u00e3o podem garantir os servi\u00e7os habituais, enquanto a administra\u00e7\u00e3o central est\u00e1 fechada por falta de energia.<\/p>\n<p>No Hospital Pr\u00edncipe Regente Carlos de Buyenzi, a dire\u00e7\u00e3o ligou para as fam\u00edlias dos falecidos para que viessem buscar os corpos, pois a c\u00e2mara frigor\u00edfica estava fora de servi\u00e7o na segunda-feira, relatou a imprensa local.<\/p>\n<p>Muitos geradores n\u00e3o podem funcionar porque est\u00e3o sem combust\u00edvel, uma vez que o Burundi enfrenta h\u00e1 tr\u00eas anos uma escassez de gasolina que se agravou nos \u00faltimos meses.<\/p>\n<p>Segundo um taxista, um litro de gasolina custa 20.000 francos burundianos (cerca de 5,8 euros) no mercado negro.<\/p>\n<p>O chefe de Estado do Burundi, Evariste Ndayishimiye, acusou recentemente os funcion\u00e1rios p\u00fablicos burundianos de conduzirem o pa\u00eds \u00e0 morte, por n\u00e3o denunciarem aqueles que lucram com o mercado negro de combust\u00edvel e divisas.<\/p>\n<p>Hoje, milhares de pessoas faziam fila na esta\u00e7\u00e3o ferrovi\u00e1ria do mercado central de Bujumbura, onde n\u00e3o circulavam autocarros, de acordo com imagens que circularam nas redes sociais.<\/p>\n<p>&#8220;No bairro de Jabe, pass\u00e1mos tr\u00eas dias sem eletricidade, tivemos \u00e1gua durante uma hora&#8221;, declarou um funcion\u00e1rio, acrescentando que &#8220;tudo est\u00e1 parado&#8221; e que &#8220;as autoridades n\u00e3o dizem nada&#8221;.<\/p>\n<p>Um funcion\u00e1rio do minist\u00e9rio da Energia afirmou que &#8220;80% da eletricidade produzida n\u00e3o est\u00e1 dispon\u00edvel desde que as obras come\u00e7aram&#8221;, estimando ainda que a situa\u00e7\u00e3o dure bastante tempo, pois &#8220;a rede data da coloniza\u00e7\u00e3o belga e est\u00e1 muito degradada&#8221;.<\/p>\n<p>O Burundi \u00e9 o pa\u00eds mais pobre do mundo em termos do Produto Interno Bruto (PIB), segundo o Banco Mundial, e 75% dos seus habitantes, cerca de 14 milh\u00f5es, vivem abaixo do limiar internacional de pobreza.<\/p>\n<\/div>\n<\/div>\n<div>\n<div><\/div>\n<\/div>\n<div>\n<div><\/div>\n<\/div>\n<div class=\"mx-3 mx-md-5 d-print-none padding-bottom-50\">\n<div class=\"row\">\n<div class=\"col-12\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Grande parte do Burundi vive desde segunda-feira sem eletricidade ou quase, com a capital Bujumbura paralisada, no momento em que o pa\u00eds enfrenta tamb\u00e9m uma grave escassez de combust\u00edveis. Os cortes de energia, programados desde segunda-feira e que devem durar at\u00e9 14 de agosto, s\u00e3o devidos a &#8220;trabalhos de liga\u00e7\u00e3o&#8221; ...<\/p>\n","protected":false},"author":9,"featured_media":188429,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[142,121,163],"tags":[],"_links":{"self":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/188428"}],"collection":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/comments?post=188428"}],"version-history":[{"count":1,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/188428\/revisions"}],"predecessor-version":[{"id":188430,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/188428\/revisions\/188430"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media\/188429"}],"wp:attachment":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media?parent=188428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/categories?post=188428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/tags?post=188428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}