{"id":185147,"date":"2025-07-11T17:04:37","date_gmt":"2025-07-11T16:04:37","guid":{"rendered":"https:\/\/rna.ao\/rna.ao\/?p=185147"},"modified":"2025-07-11T17:04:37","modified_gmt":"2025-07-11T16:04:37","slug":"angola-conta-com-o-seu-primeiro-centro-de-perfuracao-completacao-e-controlo-de-poco-certificado-internacionalmente","status":"publish","type":"post","link":"https:\/\/rna.ao\/rna.ao\/2025\/07\/11\/angola-conta-com-o-seu-primeiro-centro-de-perfuracao-completacao-e-controlo-de-poco-certificado-internacionalmente\/","title":{"rendered":"Angola conta com o seu primeiro Centro de Perfura\u00e7\u00e3o, Completa\u00e7\u00e3o e Controlo de Po\u00e7o certificado internacionalmente"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignnone size-medium wp-image-185151\" src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/07\/IMG_6532-578x770.jpeg\" alt=\"\" width=\"578\" height=\"770\" srcset=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/07\/IMG_6532-578x770.jpeg 578w, https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/07\/IMG_6532-878x1170.jpeg 878w, https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/07\/IMG_6532-768x1024.jpeg 768w, https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/07\/IMG_6532.jpeg 960w\" sizes=\"(max-width: 578px) 100vw, 578px\" \/>Angola conta, desde hoje, com o seu primeiro Centro de Perfura\u00e7\u00e3o, Completa\u00e7\u00e3o e Controlo de Po\u00e7o, certificado por empresas internacionais do sector petrol\u00edfero.<\/p>\n<p>At\u00e9 ent\u00e3o, os especialistas nesta \u00e1rea eram formados no estrangeiro, o que obrigava o pa\u00eds a gastar milhares de d\u00f3lares dos cofres do Estado.<\/p>\n<p>O ministro dos Recursos Minerais, Petr\u00f3leos e G\u00e1s, Diamantino Azevedo, assegura que o centro de perfura\u00e7\u00e3o, completa\u00e7\u00e3o e controlo de po\u00e7os desempenhar\u00e1 tarefas de grande import\u00e2ncia para o sector. Clique no \u00e1udio e ou\u00e7a:<\/p>\n\t<div class=\"qtmplayer-playlist-large\">\n\t\t<ul class=\"qtmplayer-playlist\">\n\t\t\t\n\t\t\t\t\t<li class=\"qtmplayer-trackitem\">\n\t\t<img src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/07\/IMG_6533-100x100.jpeg\" alt=\"cover\">\t\t<span \t\t\tdata-qtmplayer-cover=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/07\/IMG_6533-370x370.jpeg\"\n\t\t\t\t\t\tdata-qtmplayer-file=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/07\/DIAMANTINO-DE-AZEVEDO-13-HRS.mp3\"\n\t\t\t\t\t\tdata-qtmplayer-title=\"Angola conta com o seu primeiro Centro de Perfura\u00e7\u00e3o, Completa\u00e7\u00e3o e Controlo de Po\u00e7o certificado internacionalmente\"\n\t\t\t\t\t\tdata-qtmplayer-artist=\"Juliana Nunes\"\n\t\t\t\t\t\tdata-qtmplayer-link=\"https:\/\/rna.ao\/rna.ao\/2025\/07\/11\/angola-conta-com-o-seu-primeiro-centro-de-perfuracao-completacao-e-controlo-de-poco-certificado-internacionalmente\/\"\n\t\t\t\t\t\tdata-qtmplayer-icon=\"file_download\"\n\t\t\t\t\t\tdata-qtmplayer-type=\"track\"\n\t\t\t class=\"qtmplayer-play qtmplayer-link-sec qtmplayer-play-btn\"><i class='material-icons'>play_arrow<\/i><\/span>\n\t\t<p>\n\t\t\t<span class=\"qtmplayer-tit\">Angola conta com o seu primeiro Centro de Perfura\u00e7\u00e3o, Completa\u00e7\u00e3o e Controlo de Po\u00e7o certificado internacionalmente<\/span>\n\t\t\t<span class=\"qtmplayer-art\">Juliana Nunes<\/span>\n\t\t<\/p>\n\t<\/li>\n\t\t<\/ul>\n\t<\/div>\t\t\t\n\t\n<p>O centro, lan\u00e7ado pelo Instituto Nacional de Petr\u00f3leos &#8211; INP, tem capacidade para formar, anualmente, at\u00e9 800 especialistas nos diferentes n\u00edveis da International Well Control Forum (IWCF) e da International Association of Drilling Contractors (IADC).<\/p>\n<p>A ministra da Administra\u00e7\u00e3o P\u00fablica, Trabalho e Seguran\u00e7a Social, Teresa Dias, destacou que a institui\u00e7\u00e3o ir\u00e1 contribuir para o aumento da empregabilidade no pa\u00eds. Clique no \u00e1udio e ou\u00e7a:<\/p>\n\t<div class=\"qtmplayer-playlist-large\">\n\t\t<ul class=\"qtmplayer-playlist\">\n\t\t\t\n\t\t\t\t\t<li class=\"qtmplayer-trackitem\">\n\t\t<img src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/07\/IMG_6533-100x100.jpeg\" alt=\"cover\">\t\t<span \t\t\tdata-qtmplayer-cover=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/07\/IMG_6533-370x370.jpeg\"\n\t\t\t\t\t\tdata-qtmplayer-file=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/07\/TERESA-DIA-13HRS.mp3\"\n\t\t\t\t\t\tdata-qtmplayer-title=\"Angola conta com o seu primeiro Centro de Perfura\u00e7\u00e3o, Completa\u00e7\u00e3o e Controlo de Po\u00e7o certificado internacionalmente\"\n\t\t\t\t\t\tdata-qtmplayer-artist=\"Juliana Nunes\"\n\t\t\t\t\t\tdata-qtmplayer-link=\"https:\/\/rna.ao\/rna.ao\/2025\/07\/11\/angola-conta-com-o-seu-primeiro-centro-de-perfuracao-completacao-e-controlo-de-poco-certificado-internacionalmente\/\"\n\t\t\t\t\t\tdata-qtmplayer-icon=\"file_download\"\n\t\t\t\t\t\tdata-qtmplayer-type=\"track\"\n\t\t\t class=\"qtmplayer-play qtmplayer-link-sec qtmplayer-play-btn\"><i class='material-icons'>play_arrow<\/i><\/span>\n\t\t<p>\n\t\t\t<span class=\"qtmplayer-tit\">Angola conta com o seu primeiro Centro de Perfura\u00e7\u00e3o, Completa\u00e7\u00e3o e Controlo de Po\u00e7o certificado internacionalmente<\/span>\n\t\t\t<span class=\"qtmplayer-art\">Juliana Nunes<\/span>\n\t\t<\/p>\n\t<\/li>\n\t\t<\/ul>\n\t<\/div>\t\t\t\n\t\n<p>Por sua vez, o director-geral do Instituto Nacional de Petr\u00f3leos, Alegria Joaquim, afirmou que o centro est\u00e1 equipado com tecnologia de ponta e conta com formadores angolanos, motivo de orgulho nacional. Clique no \u00e1udio e ou\u00e7a:<\/p>\n\t<div class=\"qtmplayer-playlist-large\">\n\t\t<ul class=\"qtmplayer-playlist\">\n\t\t\t\n\t\t\t\t\t<li class=\"qtmplayer-trackitem\">\n\t\t<img src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/07\/IMG_6533-100x100.jpeg\" alt=\"cover\">\t\t<span \t\t\tdata-qtmplayer-cover=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/07\/IMG_6533-370x370.jpeg\"\n\t\t\t\t\t\tdata-qtmplayer-file=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/07\/ALEGRIA-JOAQUIM-13HRS.mp3\"\n\t\t\t\t\t\tdata-qtmplayer-title=\"Angola conta com o seu primeiro Centro de Perfura\u00e7\u00e3o, Completa\u00e7\u00e3o e Controlo de Po\u00e7o certificado internacionalmente\"\n\t\t\t\t\t\tdata-qtmplayer-artist=\"Juliana Nunes\"\n\t\t\t\t\t\tdata-qtmplayer-link=\"https:\/\/rna.ao\/rna.ao\/2025\/07\/11\/angola-conta-com-o-seu-primeiro-centro-de-perfuracao-completacao-e-controlo-de-poco-certificado-internacionalmente\/\"\n\t\t\t\t\t\tdata-qtmplayer-icon=\"file_download\"\n\t\t\t\t\t\tdata-qtmplayer-type=\"track\"\n\t\t\t class=\"qtmplayer-play qtmplayer-link-sec qtmplayer-play-btn\"><i class='material-icons'>play_arrow<\/i><\/span>\n\t\t<p>\n\t\t\t<span class=\"qtmplayer-tit\">Angola conta com o seu primeiro Centro de Perfura\u00e7\u00e3o, Completa\u00e7\u00e3o e Controlo de Po\u00e7o certificado internacionalmente<\/span>\n\t\t\t<span class=\"qtmplayer-art\">Juliana Nunes<\/span>\n\t\t<\/p>\n\t<\/li>\n\t\t<\/ul>\n\t<\/div>\t\t\t\n\t\n","protected":false},"excerpt":{"rendered":"<p>Angola conta, desde hoje, com o seu primeiro Centro de Perfura\u00e7\u00e3o, Completa\u00e7\u00e3o e Controlo de Po\u00e7o, certificado por empresas internacionais do sector petrol\u00edfero. At\u00e9 ent\u00e3o, os especialistas nesta \u00e1rea eram formados no estrangeiro, o que obrigava o pa\u00eds a gastar milhares de d\u00f3lares dos cofres do Estado. O ministro dos ...<\/p>\n","protected":false},"author":16,"featured_media":185152,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[142,121,164,163],"tags":[],"_links":{"self":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/185147"}],"collection":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/comments?post=185147"}],"version-history":[{"count":1,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/185147\/revisions"}],"predecessor-version":[{"id":185153,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/185147\/revisions\/185153"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media\/185152"}],"wp:attachment":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media?parent=185147"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/categories?post=185147"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/tags?post=185147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}