{"id":185135,"date":"2025-07-11T14:07:10","date_gmt":"2025-07-11T13:07:10","guid":{"rendered":"https:\/\/rna.ao\/rna.ao\/?p=185135"},"modified":"2025-07-11T14:07:10","modified_gmt":"2025-07-11T13:07:10","slug":"seleccao-angolana-de-futebol-sub-20-falha-final-da-taca-cosafa-ao-perder-diante-da-africa-do-sul","status":"publish","type":"post","link":"https:\/\/rna.ao\/rna.ao\/2025\/07\/11\/seleccao-angolana-de-futebol-sub-20-falha-final-da-taca-cosafa-ao-perder-diante-da-africa-do-sul\/","title":{"rendered":"Selec\u00e7\u00e3o angolana de futebol sub-20 falha final da Ta\u00e7a Cosafa ao perder diante da \u00c1frica do Sul"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignnone size-medium wp-image-185136\" src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/07\/IMG_6528-770x515.jpeg\" alt=\"\" width=\"770\" height=\"515\" srcset=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/07\/IMG_6528-770x515.jpeg 770w, https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/07\/IMG_6528-768x514.jpeg 768w, https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/07\/IMG_6528.jpeg 1070w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/>A selec\u00e7\u00e3o nacional de futebol sub-20 perdeu, na manh\u00e3 desta sexta-feira, diante da \u00c1frica do Sul, por 2-0, na primeira meia-final da competi\u00e7\u00e3o, inserida na Ta\u00e7a COSAFA.<\/p>\n<p>O advers\u00e1rio dos sul-africanos na final sair\u00e1 do duelo entre Z\u00e2mbia e Malawi, que decorre neste momento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A selec\u00e7\u00e3o nacional de futebol sub-20 perdeu, na manh\u00e3 desta sexta-feira, diante da \u00c1frica do Sul, por 2-0, na primeira meia-final da competi\u00e7\u00e3o, inserida na Ta\u00e7a COSAFA. O advers\u00e1rio dos sul-africanos na final sair\u00e1 do duelo entre Z\u00e2mbia e Malawi, que decorre neste momento.<\/p>\n","protected":false},"author":16,"featured_media":185136,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[145,125],"tags":[],"_links":{"self":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/185135"}],"collection":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/comments?post=185135"}],"version-history":[{"count":1,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/185135\/revisions"}],"predecessor-version":[{"id":185137,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/185135\/revisions\/185137"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media\/185136"}],"wp:attachment":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media?parent=185135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/categories?post=185135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/tags?post=185135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}