{"id":185060,"date":"2025-07-10T20:52:59","date_gmt":"2025-07-10T19:52:59","guid":{"rendered":"https:\/\/rna.ao\/rna.ao\/?p=185060"},"modified":"2025-07-10T20:52:59","modified_gmt":"2025-07-10T19:52:59","slug":"avaliacao-externa-de-cursos-stem-mobiliza-mais-de-400-especialistas-para-reforcar-a-qualidade-do-ensino-superior-em-angola","status":"publish","type":"post","link":"https:\/\/rna.ao\/rna.ao\/2025\/07\/10\/avaliacao-externa-de-cursos-stem-mobiliza-mais-de-400-especialistas-para-reforcar-a-qualidade-do-ensino-superior-em-angola\/","title":{"rendered":"Avalia\u00e7\u00e3o externa de cursos STEM mobiliza mais de 400 especialistas para refor\u00e7ar a qualidade do ensino superior em Angola"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-185061\" src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/07\/IMG_3730.jpeg\" alt=\"\" width=\"310\" height=\"178\" \/><br \/>\nO Instituto Nacional de Avalia\u00e7\u00e3o, Acredita\u00e7\u00e3o e Reconhecimento de Estudos do Ensino Superior (INAAREES) vai dar in\u00edcio, de 12 a 21 de Julho, \u00e0 quarta fase do processo nacional de Avalia\u00e7\u00e3o Externa e Acredita\u00e7\u00e3o da Qualidade do Ensino Superior, com foco nos cursos das \u00e1reas de Ci\u00eancias, Tecnologias, Engenharias e Matem\u00e1ticas (STEM).<\/p>\n<p>No total, 241 cursos ministrados em 70 Institui\u00e7\u00f5es de Ensino Superior (IES) ser\u00e3o submetidos a avalia\u00e7\u00e3o, sendo 121 localizados em Luanda e 120 nas demais prov\u00edncias do pa\u00eds. A opera\u00e7\u00e3o contar\u00e1 com a mobiliza\u00e7\u00e3o de 445 especialistas altamente qualificados, entre os quais 356 avaliadores externos e 89 gestores de procedimentos.<\/p>\n<p>A iniciativa integra peritos de Angola e de diversos pa\u00edses parceiros, como Brasil, Cabo Verde, Cuba, Mo\u00e7ambique, Rep\u00fablica Democr\u00e1tica do Congo, Zimbabwe, Portugal e S\u00e3o Tom\u00e9 e Pr\u00edncipe, num esfor\u00e7o conjunto para aferir a qualidade, relev\u00e2ncia e impacto social dos cursos STEM oferecidos no pa\u00eds.<\/p>\n<p>Segundo o INAAREES, o objectivo \u00e9 identificar boas pr\u00e1ticas, refor\u00e7ar a cultura de excel\u00eancia acad\u00e9mica e propor planos de melhoria com base nos resultados obtidos, promovendo o rigor e a melhoria cont\u00ednua no sistema de ensino superior.<\/p>\n<p>Esta ac\u00e7\u00e3o estrat\u00e9gica est\u00e1 alinhada ao Projecto de Desenvolvimento do Ensino Superior, Ci\u00eancia e Tecnologia (TEST), financiado pelo Banco Mundial e pela Parceria Global para a Educa\u00e7\u00e3o, que visa fortalecer a qualidade, a empregabilidade e a liga\u00e7\u00e3o entre universidades e o sector produtivo.<\/p>\n<p>Com esta avalia\u00e7\u00e3o externa, o Governo de Angola reafirma o seu compromisso com a transforma\u00e7\u00e3o sist\u00e9mica e sustent\u00e1vel do sector do ensino superior, em conson\u00e2ncia com o Plano Nacional de Desenvolvimento e o Plano Sectorial 2023\u20132027.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Instituto Nacional de Avalia\u00e7\u00e3o, Acredita\u00e7\u00e3o e Reconhecimento de Estudos do Ensino Superior (INAAREES) vai dar in\u00edcio, de 12 a 21 de Julho, \u00e0 quarta fase do processo nacional de Avalia\u00e7\u00e3o Externa e Acredita\u00e7\u00e3o da Qualidade do Ensino Superior, com foco nos cursos das \u00e1reas de Ci\u00eancias, Tecnologias, Engenharias e ...<\/p>\n","protected":false},"author":9,"featured_media":185061,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[142,121,164,163],"tags":[],"_links":{"self":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/185060"}],"collection":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/comments?post=185060"}],"version-history":[{"count":1,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/185060\/revisions"}],"predecessor-version":[{"id":185062,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/185060\/revisions\/185062"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media\/185061"}],"wp:attachment":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media?parent=185060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/categories?post=185060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/tags?post=185060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}