{"id":185030,"date":"2025-07-10T12:42:19","date_gmt":"2025-07-10T11:42:19","guid":{"rendered":"https:\/\/rna.ao\/rna.ao\/?p=185030"},"modified":"2025-07-10T12:42:49","modified_gmt":"2025-07-10T11:42:49","slug":"igreja-angolana-considera-sugestiva-exigencia-de-formacao-superior-em-teologia-para-a-acreditacao-pastores-mas-a-decisao-deve-ser-acompanhada-de-outras-medidas","status":"publish","type":"post","link":"https:\/\/rna.ao\/rna.ao\/2025\/07\/10\/igreja-angolana-considera-sugestiva-exigencia-de-formacao-superior-em-teologia-para-a-acreditacao-pastores-mas-a-decisao-deve-ser-acompanhada-de-outras-medidas\/","title":{"rendered":"Igrejas em Angola consideram sugestiva exig\u00eancia de forma\u00e7\u00e3o superior em teologia para a acredita\u00e7\u00e3o pastores, mas a decis\u00e3o deve ser acompanhada de outras medidas"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"size-full wp-image-185033 alignleft\" src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/07\/RNA-estudio-radio.jpg\" alt=\"\" width=\"303\" height=\"227\" \/>Deputados esperam tudo fazer para que a revis\u00e3o da Lei da Liberdade Religiosa e de Culto, contribua para a paz e a ordem social. Apesar da proposta n\u00e3o ter entrado ainda na Assembleia Nacional, o documento recebe j\u00e1 contribui\u00e7\u00f5es de religiosos, juristas e de acad\u00e9micos. Hoje, quinta-feira(10), o debate Angola em Directo, analisou a Proposta de Lei da Liberdade Religiosa e de Culto. As igrejas s\u00e3o un\u00e2nimes em afirmar que o diploma \u00e9 bem-vindo, apesar de existirem ainda d\u00favidas. Clique no \u00e1udio abaixo e ou\u00e7a a reportagem do Jo\u00e3o Manuel:<\/p>\n\t<div class=\"qtmplayer-playlist-large\">\n\t\t<ul class=\"qtmplayer-playlist\">\n\t\t\t\n\t\t\t\t\t<li class=\"qtmplayer-trackitem\">\n\t\t<img src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/02\/LUTAS-NAS-IGREJAS-EM-LUANDAA-100x100.jpg\" alt=\"cover\">\t\t<span \t\t\tdata-qtmplayer-cover=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/02\/LUTAS-NAS-IGREJAS-EM-LUANDAA.jpg\"\n\t\t\t\t\t\tdata-qtmplayer-file=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/07\/JOAO-MANUEL-13-HRS.mp3\"\n\t\t\t\t\t\tdata-qtmplayer-title=\"Igrejas em Angola consideram sugestiva exig\u00eancia de forma\u00e7\u00e3o superior em teologia para a acredita\u00e7\u00e3o pastores, mas a decis\u00e3o deve ser acompanhada de outras medidas\"\n\t\t\t\t\t\tdata-qtmplayer-artist=\"Ant\u00f3nio Augusto\"\n\t\t\t\t\t\tdata-qtmplayer-link=\"https:\/\/rna.ao\/rna.ao\/2025\/07\/10\/igreja-angolana-considera-sugestiva-exigencia-de-formacao-superior-em-teologia-para-a-acreditacao-pastores-mas-a-decisao-deve-ser-acompanhada-de-outras-medidas\/\"\n\t\t\t\t\t\tdata-qtmplayer-icon=\"file_download\"\n\t\t\t\t\t\tdata-qtmplayer-type=\"track\"\n\t\t\t class=\"qtmplayer-play qtmplayer-link-sec qtmplayer-play-btn\"><i class='material-icons'>play_arrow<\/i><\/span>\n\t\t<p>\n\t\t\t<span class=\"qtmplayer-tit\">Igrejas em Angola consideram sugestiva exig\u00eancia de forma\u00e7\u00e3o superior em teologia para a acredita\u00e7\u00e3o pastores, mas a decis\u00e3o deve ser acompanhada de outras medidas<\/span>\n\t\t\t<span class=\"qtmplayer-art\">Ant\u00f3nio Augusto<\/span>\n\t\t<\/p>\n\t<\/li>\n\t\t<\/ul>\n\t<\/div>\t\t\t\n\t\n","protected":false},"excerpt":{"rendered":"<p>Deputados esperam tudo fazer para que a revis\u00e3o da Lei da Liberdade Religiosa e de Culto, contribua para a paz e a ordem social. Apesar da proposta n\u00e3o ter entrado ainda na Assembleia Nacional, o documento recebe j\u00e1 contribui\u00e7\u00f5es de religiosos, juristas e de acad\u00e9micos. Hoje, quinta-feira(10), o debate Angola ...<\/p>\n","protected":false},"author":23,"featured_media":169298,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[142,121,163],"tags":[],"_links":{"self":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/185030"}],"collection":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/comments?post=185030"}],"version-history":[{"count":2,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/185030\/revisions"}],"predecessor-version":[{"id":185035,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/185030\/revisions\/185035"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media\/169298"}],"wp:attachment":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media?parent=185030"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/categories?post=185030"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/tags?post=185030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}