{"id":175127,"date":"2025-04-20T21:31:23","date_gmt":"2025-04-20T20:31:23","guid":{"rendered":"https:\/\/rna.ao\/rna.ao\/?p=175127"},"modified":"2025-04-20T21:31:23","modified_gmt":"2025-04-20T20:31:23","slug":"presidente-da-republica-regressa-a-luanda-2","status":"publish","type":"post","link":"https:\/\/rna.ao\/rna.ao\/2025\/04\/20\/presidente-da-republica-regressa-a-luanda-2\/","title":{"rendered":"Presidente da Rep\u00fablica regressa a Luanda"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignnone size-medium wp-image-175128\" src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/04\/147d54fd-3896-4592-a930-be81f46fe5b5-770x607.jpeg\" alt=\"\" width=\"770\" height=\"607\" srcset=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/04\/147d54fd-3896-4592-a930-be81f46fe5b5-770x607.jpeg 770w, https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/04\/147d54fd-3896-4592-a930-be81f46fe5b5-1170x922.jpeg 1170w, https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/04\/147d54fd-3896-4592-a930-be81f46fe5b5-768x605.jpeg 768w, https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/04\/147d54fd-3896-4592-a930-be81f46fe5b5.jpeg 1200w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/><\/p>\n<p>O Presidente da Rep\u00fablica, Jo\u00e3o Louren\u00e7o, regressou no in\u00edcio da noite deste domingo \u00a0a Luanda, depois de uma breve visita de car\u00e1cter privado \u00e0 prov\u00edncia do Namibe.<\/p>\n<p>\u00c0 chegada \u00e0 capital, o Chefe de Estado foi recebido com cumprimentos de boas-vindas pela Vice-Presidente da Rep\u00fablica, Esperan\u00e7a da Costa, e por outros membros do Executivo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Presidente da Rep\u00fablica, Jo\u00e3o Louren\u00e7o, regressou no in\u00edcio da noite deste domingo \u00a0a Luanda, depois de uma breve visita de car\u00e1cter privado \u00e0 prov\u00edncia do Namibe. \u00c0 chegada \u00e0 capital, o Chefe de Estado foi recebido com cumprimentos de boas-vindas pela Vice-Presidente da Rep\u00fablica, Esperan\u00e7a da Costa, e por ...<\/p>\n","protected":false},"author":9,"featured_media":175129,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[142,121,163],"tags":[],"_links":{"self":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/175127"}],"collection":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/comments?post=175127"}],"version-history":[{"count":1,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/175127\/revisions"}],"predecessor-version":[{"id":175130,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/175127\/revisions\/175130"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media\/175129"}],"wp:attachment":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media?parent=175127"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/categories?post=175127"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/tags?post=175127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}