{"id":173202,"date":"2025-04-01T11:53:22","date_gmt":"2025-04-01T10:53:22","guid":{"rendered":"https:\/\/rna.ao\/rna.ao\/?p=173202"},"modified":"2025-04-01T14:28:06","modified_gmt":"2025-04-01T13:28:06","slug":"chefe-de-estado-rende-homenagem-ao-general-joao-luis-neto-xietu","status":"publish","type":"post","link":"https:\/\/rna.ao\/rna.ao\/2025\/04\/01\/chefe-de-estado-rende-homenagem-ao-general-joao-luis-neto-xietu\/","title":{"rendered":"Chefe de Estado rende homenagem ao general Jo\u00e3o Lu\u00eds Neto &#8220;Xietu&#8221;"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignnone size-medium wp-image-173205\" src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/04\/IMG_1089-770x665.jpeg\" alt=\"\" width=\"770\" height=\"665\" srcset=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/04\/IMG_1089-770x665.jpeg 770w, https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/04\/IMG_1089-768x664.jpeg 768w, https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/04\/IMG_1089.jpeg 987w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/><\/p>\n<p>O Presidente da Rep\u00fablica e Comandante-Em-Chefe das For\u00e7as Armadas Angolanas, Jo\u00e3o Louren\u00e7o, prestou homenagem ao General de Ex\u00e9rcito reformado Jo\u00e3o Lu\u00eds Neto \u201cXietu\u201d, falecido recentemente em Luanda, v\u00edtima de doen\u00e7a.<\/p>\n<p>Acompanhado da Primeira Dama, Ana Dias Louren\u00e7o, o Chefe de Estado marcou presen\u00e7a no vel\u00f3rio do hist\u00f3rico nacionalista, realizado no Quartel General do Ex\u00e9rcito, onde tamb\u00e9m decorreu a cerim\u00f3nia de homenagem.<\/p>\n<p>No local, Jo\u00e3o Louren\u00e7o depositou uma coroa de flores junto \u00e0 urna do General Xietu, confortou os familiares e deixou palavras de reconhecimento no livro de condol\u00eancias.<\/p>\n<p>&nbsp;<\/p>\n<p>Na mensagem escrita, o Presidente destacou a import\u00e2ncia do General Xietu na luta pela independ\u00eancia de Angola, recordando a sua ades\u00e3o ao MPLA no final da d\u00e9cada de 1960 e o seu papel nos preparativos do hist\u00f3rico 4 de Fevereiro, data que marcou o in\u00edcio da Luta Armada de Liberta\u00e7\u00e3o Nacional.<\/p>\n<p>Jo\u00e3o Lu\u00eds Neto \u201cXietu\u201d foi o primeiro Chefe do Estado-Maior General das For\u00e7as Armadas Populares de Liberta\u00e7\u00e3o de Angola (FAPLA) e ascendeu ao mais alto posto militar, o de General de Ex\u00e9rcito, sendo distinguido ao longo da sua carreira com honrarias e medalhas de elevado valor.<\/p>\n<p>\u201cO General Xietu foi um dos mais valorosos nacionalistas e lutadores pela Independ\u00eancia e liberdade do povo angolano. A P\u00e1tria perde um dos seus melhores filhos\u201d, escreveu Jo\u00e3o Louren\u00e7o, expressando os seus p\u00easames \u00e0 fam\u00edlia, amigos e companheiros de armas. Jornalista Nelson Pedro. Clique no \u00e1udio e ou\u00e7a:<\/p>\n\t<div class=\"qtmplayer-playlist-large\">\n\t\t<ul class=\"qtmplayer-playlist\">\n\t\t\t\n\t\t\t\t\t<li class=\"qtmplayer-trackitem\">\n\t\t<img src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/04\/IMG_1090-100x100.jpeg\" alt=\"cover\">\t\t<span \t\t\tdata-qtmplayer-cover=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/04\/IMG_1090-370x370.jpeg\"\n\t\t\t\t\t\tdata-qtmplayer-file=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/04\/NELSON-PEDRO-13HRS.mp3\"\n\t\t\t\t\t\tdata-qtmplayer-title=\"Chefe de Estado rende homenagem ao general Jo\u00e3o Lu\u00eds Neto &#8220;Xietu&#8221;\"\n\t\t\t\t\t\tdata-qtmplayer-artist=\"Carla Quipungo\"\n\t\t\t\t\t\tdata-qtmplayer-link=\"https:\/\/rna.ao\/rna.ao\/2025\/04\/01\/chefe-de-estado-rende-homenagem-ao-general-joao-luis-neto-xietu\/\"\n\t\t\t\t\t\tdata-qtmplayer-icon=\"file_download\"\n\t\t\t\t\t\tdata-qtmplayer-type=\"track\"\n\t\t\t class=\"qtmplayer-play qtmplayer-link-sec qtmplayer-play-btn\"><i class='material-icons'>play_arrow<\/i><\/span>\n\t\t<p>\n\t\t\t<span class=\"qtmplayer-tit\">Chefe de Estado rende homenagem ao general Jo\u00e3o Lu\u00eds Neto &#8220;Xietu&#8221;<\/span>\n\t\t\t<span class=\"qtmplayer-art\">Carla Quipungo<\/span>\n\t\t<\/p>\n\t<\/li>\n\t\t<\/ul>\n\t<\/div>\t\t\t\n\t\n","protected":false},"excerpt":{"rendered":"<p>O Presidente da Rep\u00fablica e Comandante-Em-Chefe das For\u00e7as Armadas Angolanas, Jo\u00e3o Louren\u00e7o, prestou homenagem ao General de Ex\u00e9rcito reformado Jo\u00e3o Lu\u00eds Neto \u201cXietu\u201d, falecido recentemente em Luanda, v\u00edtima de doen\u00e7a. Acompanhado da Primeira Dama, Ana Dias Louren\u00e7o, o Chefe de Estado marcou presen\u00e7a no vel\u00f3rio do hist\u00f3rico nacionalista, realizado no ...<\/p>\n","protected":false},"author":9,"featured_media":173206,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[142,121,164,163],"tags":[],"_links":{"self":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/173202"}],"collection":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/comments?post=173202"}],"version-history":[{"count":2,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/173202\/revisions"}],"predecessor-version":[{"id":173239,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/173202\/revisions\/173239"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media\/173206"}],"wp:attachment":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media?parent=173202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/categories?post=173202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/tags?post=173202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}