{"id":173165,"date":"2025-04-01T10:21:17","date_gmt":"2025-04-01T09:21:17","guid":{"rendered":"https:\/\/rna.ao\/rna.ao\/?p=173165"},"modified":"2025-04-01T13:39:29","modified_gmt":"2025-04-01T12:39:29","slug":"luanda-esta-sob-alerta-amarelo-chuva-desta-terca-feira-causa-a-morte-de-um-adolescente-no-sambizanga","status":"publish","type":"post","link":"https:\/\/rna.ao\/rna.ao\/2025\/04\/01\/luanda-esta-sob-alerta-amarelo-chuva-desta-terca-feira-causa-a-morte-de-um-adolescente-no-sambizanga\/","title":{"rendered":"Luanda est\u00e1 sob alerta amarelo. Chuva desta ter\u00e7a-feira aponta para a morte de um adolescente na Samba"},"content":{"rendered":"<p style=\"font-weight: 400;\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-173169\" src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/04\/IMG_1867.jpeg\" alt=\"\" width=\"720\" height=\"540\" \/>Chove em Luanda desde as primeiras horas desta manh\u00e3. No balan\u00e7o provis\u00f3rio dos Servi\u00e7os de Protec\u00e7\u00e3o Civil e Bombeiros consta a morte de um menor de 14 anos, no munic\u00edpio da Samba.<\/p>\n<p style=\"font-weight: 400;\">De acordo com o Porta-voz dos Servi\u00e7os de Protec\u00e7\u00e3o Civil e Bombeiros de Luanda, Wilson Baptista, h\u00e1 nesta altura v\u00e1rias zonas inundadas e muitas ruas intransit\u00e1veis.<\/p>\n<p style=\"font-weight: 400;\">Wilson Baptista revela tamb\u00e9m que Luanda est\u00e1 sob alerta amarelo desde ontem. Clique no \u00e1udio e ou\u00e7a:<\/p>\n\t<div class=\"qtmplayer-playlist-large\">\n\t\t<ul class=\"qtmplayer-playlist\">\n\t\t\t\n\t\t\t\t\t<li class=\"qtmplayer-trackitem\">\n\t\t<img src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/04\/IMG_1867-100x100.jpeg\" alt=\"cover\">\t\t<span \t\t\tdata-qtmplayer-cover=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/04\/IMG_1867-370x370.jpeg\"\n\t\t\t\t\t\tdata-qtmplayer-file=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/04\/WILSON-BAPTISTA-08HRS-BOOM.mp3\"\n\t\t\t\t\t\tdata-qtmplayer-title=\"Luanda est\u00e1 sob alerta amarelo. Chuva desta ter\u00e7a-feira aponta para a morte de um adolescente na Samba\"\n\t\t\t\t\t\tdata-qtmplayer-artist=\"Juliana Nunes\"\n\t\t\t\t\t\tdata-qtmplayer-link=\"https:\/\/rna.ao\/rna.ao\/2025\/04\/01\/luanda-esta-sob-alerta-amarelo-chuva-desta-terca-feira-causa-a-morte-de-um-adolescente-no-sambizanga\/\"\n\t\t\t\t\t\tdata-qtmplayer-icon=\"file_download\"\n\t\t\t\t\t\tdata-qtmplayer-type=\"track\"\n\t\t\t class=\"qtmplayer-play qtmplayer-link-sec qtmplayer-play-btn\"><i class='material-icons'>play_arrow<\/i><\/span>\n\t\t<p>\n\t\t\t<span class=\"qtmplayer-tit\">Luanda est\u00e1 sob alerta amarelo. Chuva desta ter\u00e7a-feira aponta para a morte de um adolescente na Samba<\/span>\n\t\t\t<span class=\"qtmplayer-art\">Juliana Nunes<\/span>\n\t\t<\/p>\n\t<\/li>\n\t\t<\/ul>\n\t<\/div>\t\t\t\n\t\n","protected":false},"excerpt":{"rendered":"<p>Chove em Luanda desde as primeiras horas desta manh\u00e3. No balan\u00e7o provis\u00f3rio dos Servi\u00e7os de Protec\u00e7\u00e3o Civil e Bombeiros consta a morte de um menor de 14 anos, no munic\u00edpio da Samba. De acordo com o Porta-voz dos Servi\u00e7os de Protec\u00e7\u00e3o Civil e Bombeiros de Luanda, Wilson Baptista, h\u00e1 nesta ...<\/p>\n","protected":false},"author":16,"featured_media":173169,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[142,121,141,133,164,163],"tags":[],"_links":{"self":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/173165"}],"collection":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/comments?post=173165"}],"version-history":[{"count":5,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/173165\/revisions"}],"predecessor-version":[{"id":173222,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/173165\/revisions\/173222"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media\/173169"}],"wp:attachment":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media?parent=173165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/categories?post=173165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/tags?post=173165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}