{"id":172956,"date":"2025-03-30T12:33:45","date_gmt":"2025-03-30T11:33:45","guid":{"rendered":"https:\/\/rna.ao\/rna.ao\/?p=172956"},"modified":"2025-03-31T07:23:15","modified_gmt":"2025-03-31T06:23:15","slug":"proximo-forum-de-negocio-e-conectividade-vai-ser-na-provincia-do-uige","status":"publish","type":"post","link":"https:\/\/rna.ao\/rna.ao\/2025\/03\/30\/proximo-forum-de-negocio-e-conectividade-vai-ser-na-provincia-do-uige\/","title":{"rendered":"Pr\u00f3ximo F\u00f3rum de Neg\u00f3cios e Conectividade marcado para a prov\u00edncia do U\u00edge"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"wp-image-172780 aligncenter\" src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/03\/IMG_1825-770x513.jpeg\" alt=\"\" width=\"503\" height=\"335\" srcset=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/03\/IMG_1825-770x513.jpeg 770w, https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/03\/IMG_1825-1170x780.jpeg 1170w, https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/03\/IMG_1825-768x512.jpeg 768w, https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/03\/IMG_1825-1536x1024.jpeg 1536w, https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/03\/IMG_1825.jpeg 1560w\" sizes=\"(max-width: 503px) 100vw, 503px\" \/>A prov\u00edncia do U\u00edge vai acolher a pr\u00f3xima edi\u00e7\u00e3o do F\u00f3rum de Neg\u00f3cios e Conectividade, uma iniciativa do Grupo MediaNova.<\/p>\n<p>A organiza\u00e7\u00e3o fez um balan\u00e7o positivo da edi\u00e7\u00e3o deste ano, realizada na prov\u00edncia da Hu\u00edla, considerando que o certame superou as expectativas a todos os n\u00edveis.<\/p>\n<p>Esperavam-se pelo menos 100 participantes, mas o n\u00famero foi 160.<\/p>\n<p>O F\u00f3rum de Neg\u00f3cios e Conectividade decorreu sob o lema: \u201cA carta geol\u00f3gica da Huila, Namibe, Cunene e o agroneg\u00f3cio da regi\u00e3o\u201d. \u200eO evento juntou v\u00e1rios empres\u00e1rios que debateram as potencialidades minerais da Hu\u00edla e da carta geol\u00f3gica do Sul do pa\u00eds.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A prov\u00edncia do U\u00edge vai acolher a pr\u00f3xima edi\u00e7\u00e3o do F\u00f3rum de Neg\u00f3cios e Conectividade, uma iniciativa do Grupo MediaNova. A organiza\u00e7\u00e3o fez um balan\u00e7o positivo da edi\u00e7\u00e3o deste ano, realizada na prov\u00edncia da Hu\u00edla, considerando que o certame superou as expectativas a todos os n\u00edveis. Esperavam-se pelo menos 100 ...<\/p>\n","protected":false},"author":23,"featured_media":155142,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[142,121,164,163],"tags":[],"_links":{"self":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/172956"}],"collection":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/comments?post=172956"}],"version-history":[{"count":3,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/172956\/revisions"}],"predecessor-version":[{"id":172986,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/172956\/revisions\/172986"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media\/155142"}],"wp:attachment":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media?parent=172956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/categories?post=172956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/tags?post=172956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}