{"id":172870,"date":"2025-03-29T02:41:03","date_gmt":"2025-03-29T01:41:03","guid":{"rendered":"https:\/\/rna.ao\/rna.ao\/?p=172870"},"modified":"2025-03-29T02:41:03","modified_gmt":"2025-03-29T01:41:03","slug":"nova-geracao-de-escritores-reconhecem-grandeza-de-antonio-de-assis-junior","status":"publish","type":"post","link":"https:\/\/rna.ao\/rna.ao\/2025\/03\/29\/nova-geracao-de-escritores-reconhecem-grandeza-de-antonio-de-assis-junior\/","title":{"rendered":"Nova gera\u00e7\u00e3o de escritores reconhecem grandeza de Ant\u00f3nio de Assis J\u00fanior"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"size-full wp-image-172873 alignleft\" src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/03\/Antonio-de-Assis-Junior.jpg\" alt=\"\" width=\"189\" height=\"200\" \/>O escritor, advogado e jornalista, Ant\u00f3nio de Assis J\u00fanior, foi homenageado na sexta-feira (28), pelos feitos alcan\u00e7ados no \u00e2mbito da literatura angolana. Uma iniciativa da Comiss\u00e3o Nacional do Instituto Internacional da L\u00edngua Portuguesa e Academia Diplom\u00e1tica Ven\u00e2ncio de Moura.<\/p>\n<p>O prelector Akiz Neto que falava em representa\u00e7\u00e3o do Secret\u00e1rio Geral da Uni\u00e3o dos Escritores Angolanos, David Capelengue, descreveu Ant\u00f3nio de Assis J\u00fanior como sendo uma das figuras de maior realce na vida intelectual, tendo se destacado no in\u00edcio do s\u00e9culo XIX e no princ\u00edpio do s\u00e9culo XX, deixando v\u00e1rias obras. Al\u00e9m de escritor foi tamb\u00e9m procurador judicial, e defendia os direitos de posse de terra dos cidad\u00e3os. Clique no \u00e1udio e ou\u00e7a:<\/p>\n\t<div class=\"qtmplayer-playlist-large\">\n\t\t<ul class=\"qtmplayer-playlist\">\n\t\t\t\n\t\t\t\t\t<li class=\"qtmplayer-trackitem\">\n\t\t<img src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/03\/Antonio-de-Assis-Junior-100x100.jpg\" alt=\"cover\">\t\t<span \t\t\tdata-qtmplayer-cover=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/03\/Antonio-de-Assis-Junior.jpg\"\n\t\t\t\t\t\tdata-qtmplayer-file=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/03\/AKIS-NETO-20HRS.mp3\"\n\t\t\t\t\t\tdata-qtmplayer-title=\"Nova gera\u00e7\u00e3o de escritores reconhecem grandeza de Ant\u00f3nio de Assis J\u00fanior\"\n\t\t\t\t\t\tdata-qtmplayer-artist=\"Ant\u00f3nio Augusto\"\n\t\t\t\t\t\tdata-qtmplayer-link=\"https:\/\/rna.ao\/rna.ao\/2025\/03\/29\/nova-geracao-de-escritores-reconhecem-grandeza-de-antonio-de-assis-junior\/\"\n\t\t\t\t\t\tdata-qtmplayer-icon=\"file_download\"\n\t\t\t\t\t\tdata-qtmplayer-type=\"track\"\n\t\t\t class=\"qtmplayer-play qtmplayer-link-sec qtmplayer-play-btn\"><i class='material-icons'>play_arrow<\/i><\/span>\n\t\t<p>\n\t\t\t<span class=\"qtmplayer-tit\">Nova gera\u00e7\u00e3o de escritores reconhecem grandeza de Ant\u00f3nio de Assis J\u00fanior<\/span>\n\t\t\t<span class=\"qtmplayer-art\">Ant\u00f3nio Augusto<\/span>\n\t\t<\/p>\n\t<\/li>\n\t\t<\/ul>\n\t<\/div>\t\t\t\n\t\n<p>E, o neto do Escritor, advogado e jornalista Ant\u00f3nio Assis J\u00fanior, Ant\u00f3nio Assis que falou em representa\u00e7\u00e3o da fam\u00edlia agradeceu o gesto dos organizadores do evento. Ant\u00f3nio Assis disse que o seu av\u00f4 deixou um grande legado que \u00e9 de ser solid\u00e1rio. Clique no \u00e1udio e ou\u00e7a:<\/p>\n\t<div class=\"qtmplayer-playlist-large\">\n\t\t<ul class=\"qtmplayer-playlist\">\n\t\t\t\n\t\t\t\t\t<li class=\"qtmplayer-trackitem\">\n\t\t<img src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/03\/Antonio-de-Assis-Junior-100x100.jpg\" alt=\"cover\">\t\t<span \t\t\tdata-qtmplayer-cover=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/03\/Antonio-de-Assis-Junior.jpg\"\n\t\t\t\t\t\tdata-qtmplayer-file=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2025\/03\/ANTONIO-DE-ASSIS-20HRS.mp3\"\n\t\t\t\t\t\tdata-qtmplayer-title=\"Nova gera\u00e7\u00e3o de escritores reconhecem grandeza de Ant\u00f3nio de Assis J\u00fanior\"\n\t\t\t\t\t\tdata-qtmplayer-artist=\"Ant\u00f3nio Augusto\"\n\t\t\t\t\t\tdata-qtmplayer-link=\"https:\/\/rna.ao\/rna.ao\/2025\/03\/29\/nova-geracao-de-escritores-reconhecem-grandeza-de-antonio-de-assis-junior\/\"\n\t\t\t\t\t\tdata-qtmplayer-icon=\"file_download\"\n\t\t\t\t\t\tdata-qtmplayer-type=\"track\"\n\t\t\t class=\"qtmplayer-play qtmplayer-link-sec qtmplayer-play-btn\"><i class='material-icons'>play_arrow<\/i><\/span>\n\t\t<p>\n\t\t\t<span class=\"qtmplayer-tit\">Nova gera\u00e7\u00e3o de escritores reconhecem grandeza de Ant\u00f3nio de Assis J\u00fanior<\/span>\n\t\t\t<span class=\"qtmplayer-art\">Ant\u00f3nio Augusto<\/span>\n\t\t<\/p>\n\t<\/li>\n\t\t<\/ul>\n\t<\/div>\t\t\t\n\t\n","protected":false},"excerpt":{"rendered":"<p>O escritor, advogado e jornalista, Ant\u00f3nio de Assis J\u00fanior, foi homenageado na sexta-feira (28), pelos feitos alcan\u00e7ados no \u00e2mbito da literatura angolana. Uma iniciativa da Comiss\u00e3o Nacional do Instituto Internacional da L\u00edngua Portuguesa e Academia Diplom\u00e1tica Ven\u00e2ncio de Moura. O prelector Akiz Neto que falava em representa\u00e7\u00e3o do Secret\u00e1rio Geral ...<\/p>\n","protected":false},"author":23,"featured_media":172873,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[141,133,164],"tags":[],"_links":{"self":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/172870"}],"collection":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/comments?post=172870"}],"version-history":[{"count":1,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/172870\/revisions"}],"predecessor-version":[{"id":172874,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/172870\/revisions\/172874"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media\/172873"}],"wp:attachment":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media?parent=172870"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/categories?post=172870"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/tags?post=172870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}