{"id":157147,"date":"2024-10-02T10:42:04","date_gmt":"2024-10-02T09:42:04","guid":{"rendered":"https:\/\/rna.ao\/rna.ao\/?p=157147"},"modified":"2024-10-02T10:42:04","modified_gmt":"2024-10-02T09:42:04","slug":"acidente-de-viacao-no-zaire-causa-dois-mortos-e-vinte-e-cinco-feridos","status":"publish","type":"post","link":"https:\/\/rna.ao\/rna.ao\/2024\/10\/02\/acidente-de-viacao-no-zaire-causa-dois-mortos-e-vinte-e-cinco-feridos\/","title":{"rendered":"Acidente de via\u00e7\u00e3o no Zaire causa dois mortos e vinte e cinco feridos"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"size-full wp-image-128760 aligncenter\" src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2024\/01\/Acidente-de-viacao-no-Uige-1.jpg\" alt=\"\" width=\"308\" height=\"173\" \/>Duas pessoas morreram e vinte e cinco outras ficaram feridas em consequ\u00eancia de um acidente de via\u00e7\u00e3o que envolveu uma carinha Canter que fazia o trajecto Tomboco, Mbanza Congo. O excesso de velocidade esteve na origem do acidente da viatura que para al\u00e9m de mercadoria transporta tamb\u00e9m enumeras pessoas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Duas pessoas morreram e vinte e cinco outras ficaram feridas em consequ\u00eancia de um acidente de via\u00e7\u00e3o que envolveu uma carinha Canter que fazia o trajecto Tomboco, Mbanza Congo. O excesso de velocidade esteve na origem do acidente da viatura que para al\u00e9m de mercadoria transporta tamb\u00e9m enumeras pessoas.<\/p>\n","protected":false},"author":15,"featured_media":128760,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[121,163],"tags":[],"_links":{"self":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/157147"}],"collection":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/comments?post=157147"}],"version-history":[{"count":1,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/157147\/revisions"}],"predecessor-version":[{"id":157148,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/157147\/revisions\/157148"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media\/128760"}],"wp:attachment":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media?parent=157147"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/categories?post=157147"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/tags?post=157147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}