{"id":145818,"date":"2024-06-27T00:19:55","date_gmt":"2024-06-26T23:19:55","guid":{"rendered":"https:\/\/rna.ao\/rna.ao\/?p=145818"},"modified":"2024-06-27T00:23:49","modified_gmt":"2024-06-26T23:23:49","slug":"presidente-joao-lourenco-felicita-povo-mocambicano-pelo-49-aniversario-da-independencia","status":"publish","type":"post","link":"https:\/\/rna.ao\/rna.ao\/2024\/06\/27\/presidente-joao-lourenco-felicita-povo-mocambicano-pelo-49-aniversario-da-independencia\/","title":{"rendered":"Presidente Jo\u00e3o Louren\u00e7o felicita povo Mo\u00e7ambicano pelo 49\u00b0 anivers\u00e1rio da Independ\u00eancia"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignnone size-medium wp-image-145819\" src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2024\/06\/IMG_2703-770x667.jpeg\" alt=\"\" width=\"770\" height=\"667\" srcset=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2024\/06\/IMG_2703-770x667.jpeg 770w, https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2024\/06\/IMG_2703-768x666.jpeg 768w, https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2024\/06\/IMG_2703.jpeg 990w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/>Por ocasi\u00e3o do 49\u00b0 anivers\u00e1rio da Independ\u00eancia de Mo\u00e7ambique assinalados esta ter\u00e7a-feira, 25 de Junho, o Presidente da Rep\u00fablica, Jo\u00e3o Louren\u00e7o, felicitou o povo mo\u00e7ambicano e o Governo daquele pa\u00eds irm\u00e3o.<\/p>\n<p>Em mensagem enviada ao Presidente Filipe Nyusi, o Presidente de Angola sublinha &#8220;Satisfaz-me constatar, nesta data memor\u00e1vel, os esfor\u00e7os que v\u00eam sendo desenvolvidos por Vossa Excel\u00eancia e pelo Governo que dirige, com o apoio da cidadania mo\u00e7ambicana, no sentido da harmoniza\u00e7\u00e3o da vida interna do vosso pa\u00eds, da conc\u00f3rdia entre os mo\u00e7ambicanos, da consolida\u00e7\u00e3o da democracia e o restabelecimento da seguran\u00e7a plena em todo o territ\u00f3rio nacional e na regi\u00e3o austral do continente, de uma maneira geral&#8221;.<\/p>\n<p>O Chefe de Estado aproveitou a ocasi\u00e3o para reafirmar o interesse de Angola em continuar a estreitar os la\u00e7os de amizade e de solidariedade que unem os povos angolano e mo\u00e7ambicano, &#8220;com a cria\u00e7\u00e3o de novas oportunidades de colabora\u00e7\u00e3o, capazes de favorecer a concretiza\u00e7\u00e3o das aspira\u00e7\u00f5es dos respectivos cidad\u00e3os ao desenvolvimento e ao bem-estar&#8221;.<\/p>\n<p>A 25 de Junho de 1975 foi proclamada a independ\u00eancia de Mo\u00e7ambique, territ\u00f3rio colonizado pelo imp\u00e9rio portugu\u00eas a partir de finais do s\u00e9c. XV e in\u00edcios do s\u00e9c. XVI.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por ocasi\u00e3o do 49\u00b0 anivers\u00e1rio da Independ\u00eancia de Mo\u00e7ambique assinalados esta ter\u00e7a-feira, 25 de Junho, o Presidente da Rep\u00fablica, Jo\u00e3o Louren\u00e7o, felicitou o povo mo\u00e7ambicano e o Governo daquele pa\u00eds irm\u00e3o. Em mensagem enviada ao Presidente Filipe Nyusi, o Presidente de Angola sublinha &#8220;Satisfaz-me constatar, nesta data memor\u00e1vel, os esfor\u00e7os ...<\/p>\n","protected":false},"author":16,"featured_media":145819,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[142,121,163],"tags":[],"_links":{"self":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/145818"}],"collection":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/comments?post=145818"}],"version-history":[{"count":3,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/145818\/revisions"}],"predecessor-version":[{"id":145822,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/145818\/revisions\/145822"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media\/145819"}],"wp:attachment":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media?parent=145818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/categories?post=145818"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/tags?post=145818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}