{"id":145703,"date":"2024-06-25T19:09:49","date_gmt":"2024-06-25T18:09:49","guid":{"rendered":"https:\/\/rna.ao\/rna.ao\/?p=145703"},"modified":"2024-06-25T19:09:49","modified_gmt":"2024-06-25T18:09:49","slug":"sic-no-namibe-trava-a-entrada-no-circuito-comercial-de-4-500-usd-falsos","status":"publish","type":"post","link":"https:\/\/rna.ao\/rna.ao\/2024\/06\/25\/sic-no-namibe-trava-a-entrada-no-circuito-comercial-de-4-500-usd-falsos\/","title":{"rendered":"Sic no Namibe trava a entrada no circuito comercial de 4.500 USD falsos"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignnone size-medium wp-image-145705\" src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2024\/06\/f8611e78-36f0-44d0-9c89-5da844b69083-374x770.jpeg\" alt=\"\" width=\"374\" height=\"770\" srcset=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2024\/06\/f8611e78-36f0-44d0-9c89-5da844b69083-374x770.jpeg 374w, https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2024\/06\/f8611e78-36f0-44d0-9c89-5da844b69083.jpeg 504w\" sizes=\"(max-width: 374px) 100vw, 374px\" \/>Quatro mil e quinhentos d\u00f3lares Norte Americanos falsos foram encontrados em posse de 5 cidad\u00e3s nacionais de 16 a 23 anos de idade na Prov\u00edncia do Namibe.<\/p>\n<p>Segundo o SIC &#8211; Servi\u00e7os de Investiga\u00e7\u00e3o Criminal os acusados foram denunciados pelo propriet\u00e1rio de um estabelecimento comercial onde pretendiam trocar 200 D\u00f3lares Norte americanos. Jornalista Elias Guito. Clique no \u00e1udio e ou\u00e7a:<\/p>\n\t<div class=\"qtmplayer-playlist-large\">\n\t\t<ul class=\"qtmplayer-playlist\">\n\t\t\t\n\t\t\t\t\t<li class=\"qtmplayer-trackitem\">\n\t\t<img src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2024\/06\/4b566410-162b-4f16-a943-992e45637591-100x100.jpeg\" alt=\"cover\">\t\t<span \t\t\tdata-qtmplayer-cover=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2024\/06\/4b566410-162b-4f16-a943-992e45637591-370x370.jpeg\"\n\t\t\t\t\t\tdata-qtmplayer-file=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2024\/06\/PECA-ELIAS-GUITO-DIA-25-MOEDAS-FALSAS-NO-MERCADO-.mp3\"\n\t\t\t\t\t\tdata-qtmplayer-title=\"Sic no Namibe trava a entrada no circuito comercial de 4.500 USD falsos\"\n\t\t\t\t\t\tdata-qtmplayer-artist=\"Juliana Nunes\"\n\t\t\t\t\t\tdata-qtmplayer-link=\"https:\/\/rna.ao\/rna.ao\/2024\/06\/25\/sic-no-namibe-trava-a-entrada-no-circuito-comercial-de-4-500-usd-falsos\/\"\n\t\t\t\t\t\tdata-qtmplayer-icon=\"file_download\"\n\t\t\t\t\t\tdata-qtmplayer-type=\"track\"\n\t\t\t class=\"qtmplayer-play qtmplayer-link-sec qtmplayer-play-btn\"><i class='material-icons'>play_arrow<\/i><\/span>\n\t\t<p>\n\t\t\t<span class=\"qtmplayer-tit\">Sic no Namibe trava a entrada no circuito comercial de 4.500 USD falsos<\/span>\n\t\t\t<span class=\"qtmplayer-art\">Juliana Nunes<\/span>\n\t\t<\/p>\n\t<\/li>\n\t\t<\/ul>\n\t<\/div>\t\t\t\n\t\n","protected":false},"excerpt":{"rendered":"<p>Quatro mil e quinhentos d\u00f3lares Norte Americanos falsos foram encontrados em posse de 5 cidad\u00e3s nacionais de 16 a 23 anos de idade na Prov\u00edncia do Namibe. Segundo o SIC &#8211; Servi\u00e7os de Investiga\u00e7\u00e3o Criminal os acusados foram denunciados pelo propriet\u00e1rio de um estabelecimento comercial onde pretendiam trocar 200 D\u00f3lares ...<\/p>\n","protected":false},"author":16,"featured_media":145706,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[142,121],"tags":[],"_links":{"self":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/145703"}],"collection":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/comments?post=145703"}],"version-history":[{"count":1,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/145703\/revisions"}],"predecessor-version":[{"id":145707,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/145703\/revisions\/145707"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media\/145706"}],"wp:attachment":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media?parent=145703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/categories?post=145703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/tags?post=145703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}