{"id":135145,"date":"2024-03-19T11:52:51","date_gmt":"2024-03-19T10:52:51","guid":{"rendered":"https:\/\/rna.ao\/rna.ao\/?p=135145"},"modified":"2024-03-19T11:52:51","modified_gmt":"2024-03-19T10:52:51","slug":"le-congo-celebre-le-47eme-anniversaire-de-la-mort-de-marien-ngouabi","status":"publish","type":"post","link":"https:\/\/rna.ao\/rna.ao\/2024\/03\/19\/le-congo-celebre-le-47eme-anniversaire-de-la-mort-de-marien-ngouabi\/","title":{"rendered":"Le Congo celebre le  47eme anniversaire de la mort de Marien Ngouabi"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"size-full wp-image-135150 alignleft\" src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2024\/03\/president-Marien-NGOUABI.jpg\" alt=\"\" width=\"225\" height=\"225\" srcset=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2024\/03\/president-Marien-NGOUABI.jpg 225w, https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2024\/03\/president-Marien-NGOUABI-150x150.jpg 150w, https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2024\/03\/president-Marien-NGOUABI-100x100.jpg 100w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/>Le 18 mars 2024 ,le Congo a celebr\u00e9,\u00a0 le 47e anniversaire de la disparition du pr\u00e9sident\u00a0 et hero de la Republique du Congo Brazzaville , Marien Ngouabi. A Luanda,la capitale angolaise, la communaute\u00a0 congolaise s\u2019est souvenus du pr\u00e9sident Marien NGOUABI, assassin\u00e9 le 18 mars 1977. En ce jour de souvenir, l\u2019ambassade du Congo en Angola, dirige par l\u2019ambassadeur , Christ Bonaventure Engobo anisi que\u00a0 les membres de la famille de l\u2019imortel Marien Ngoua, lui ont rendu hommage\u00a047 ans,jour pour jour, apres la disparition de Marien Ngouabi, sa vie et son oeuvre demeurent precieuses pour les\u00a0 congolais, d\u2019apres le c\u00f4nsul de l\u2019ambassade du Congo Brazzaville en Angola,Mr. Galloy Gouala Marius Aime .<\/p>\n\t<div class=\"qtmplayer-playlist-large\">\n\t\t<ul class=\"qtmplayer-playlist\">\n\t\t\t\n\t\t\t\t\t<li class=\"qtmplayer-trackitem\">\n\t\t<img src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2024\/03\/president-Marien-NGOUABIi-100x100.jpg\" alt=\"cover\">\t\t<span \t\t\tdata-qtmplayer-cover=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2024\/03\/president-Marien-NGOUABIi.jpg\"\n\t\t\t\t\t\tdata-qtmplayer-file=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2024\/03\/FILHO-DE-MARIEN-NGOUABI.mp3\"\n\t\t\t\t\t\tdata-qtmplayer-title=\"Le Congo celebre le  47eme anniversaire de la mort de Marien Ngouabi\"\n\t\t\t\t\t\tdata-qtmplayer-artist=\"RNA\"\n\t\t\t\t\t\tdata-qtmplayer-link=\"https:\/\/rna.ao\/rna.ao\/2024\/03\/19\/le-congo-celebre-le-47eme-anniversaire-de-la-mort-de-marien-ngouabi\/\"\n\t\t\t\t\t\tdata-qtmplayer-icon=\"file_download\"\n\t\t\t\t\t\tdata-qtmplayer-type=\"track\"\n\t\t\t class=\"qtmplayer-play qtmplayer-link-sec qtmplayer-play-btn\"><i class='material-icons'>play_arrow<\/i><\/span>\n\t\t<p>\n\t\t\t<span class=\"qtmplayer-tit\">Le Congo celebre le  47eme anniversaire de la mort de Marien Ngouabi<\/span>\n\t\t\t<span class=\"qtmplayer-art\">RNA<\/span>\n\t\t<\/p>\n\t<\/li>\n\t\t<\/ul>\n\t<\/div>\t\t\t\n\t\n<p>Le diplomate congolais remercie, le peuple angolais\u00a0 et a evoque sur les relations d\u2019amitie entre Marien Ngouabi et le pere fondateur de la nation angolaise ,Agostino Neto. De son cote,le fils du regrette president,et conseille special du president Sassou Nguesso ,Mr.\u00a0\u00a0 Gouabi Dominique\u00a0 a parle de la memoire de son pere, et a profite de l\u2019occasion pour remercie les peuples de l\u2019Angola pour avoir imortalise Marien Ngouabi en Angola.<\/p>\n\t<div class=\"qtmplayer-playlist-large\">\n\t\t<ul class=\"qtmplayer-playlist\">\n\t\t\t\n\t\t\t\t\t<li class=\"qtmplayer-trackitem\">\n\t\t<img src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2024\/03\/president-Marien-NGOUABIi-100x100.jpg\" alt=\"cover\">\t\t<span \t\t\tdata-qtmplayer-cover=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2024\/03\/president-Marien-NGOUABIi.jpg\"\n\t\t\t\t\t\tdata-qtmplayer-file=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2024\/03\/CONSUL-CONGO-BRAZZA.mp3\"\n\t\t\t\t\t\tdata-qtmplayer-title=\"Le Congo celebre le  47eme anniversaire de la mort de Marien Ngouabi\"\n\t\t\t\t\t\tdata-qtmplayer-artist=\"RNA\"\n\t\t\t\t\t\tdata-qtmplayer-link=\"https:\/\/rna.ao\/rna.ao\/2024\/03\/19\/le-congo-celebre-le-47eme-anniversaire-de-la-mort-de-marien-ngouabi\/\"\n\t\t\t\t\t\tdata-qtmplayer-icon=\"file_download\"\n\t\t\t\t\t\tdata-qtmplayer-type=\"track\"\n\t\t\t class=\"qtmplayer-play qtmplayer-link-sec qtmplayer-play-btn\"><i class='material-icons'>play_arrow<\/i><\/span>\n\t\t<p>\n\t\t\t<span class=\"qtmplayer-tit\">Le Congo celebre le  47eme anniversaire de la mort de Marien Ngouabi<\/span>\n\t\t\t<span class=\"qtmplayer-art\">RNA<\/span>\n\t\t<\/p>\n\t<\/li>\n\t\t<\/ul>\n\t<\/div>\t\t\t\n\t\n","protected":false},"excerpt":{"rendered":"<p>Le 18 mars 2024 ,le Congo a celebr\u00e9,\u00a0 le 47e anniversaire de la disparition du pr\u00e9sident\u00a0 et hero de la Republique du Congo Brazzaville , Marien Ngouabi. A Luanda,la capitale angolaise, la communaute\u00a0 congolaise s\u2019est souvenus du pr\u00e9sident Marien NGOUABI, assassin\u00e9 le 18 mars 1977. En ce jour de souvenir, ...<\/p>\n","protected":false},"author":8,"featured_media":135151,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[143,137],"tags":[],"_links":{"self":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/135145"}],"collection":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/comments?post=135145"}],"version-history":[{"count":1,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/135145\/revisions"}],"predecessor-version":[{"id":135152,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/135145\/revisions\/135152"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media\/135151"}],"wp:attachment":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media?parent=135145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/categories?post=135145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/tags?post=135145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}