{"id":135136,"date":"2024-03-19T10:53:48","date_gmt":"2024-03-19T09:53:48","guid":{"rendered":"https:\/\/rna.ao\/rna.ao\/?p=135136"},"modified":"2024-03-19T11:03:47","modified_gmt":"2024-03-19T10:03:47","slug":"tres-candidatos-querem-o-comando-do-1o-de-agosto-mas-somente-um-vai-restruturar-o-clube","status":"publish","type":"post","link":"https:\/\/rna.ao\/rna.ao\/2024\/03\/19\/tres-candidatos-querem-o-comando-do-1o-de-agosto-mas-somente-um-vai-restruturar-o-clube\/","title":{"rendered":"Tr\u00eas candidatos querem o comando do 1\u00ba de Agosto, mas somente um vai tirar o clube da crise financeira que se encontra"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"size-full wp-image-135137 aligncenter\" src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2024\/03\/Dagosto-1.jpg\" alt=\"\" width=\"372\" height=\"213\" srcset=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2024\/03\/Dagosto-1.jpg 372w, https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2024\/03\/Dagosto-1-370x213.jpg 370w\" sizes=\"(max-width: 372px) 100vw, 372px\" \/>Os tr\u00eas candidatos \u00e0 presid\u00eancia do 1\u00ba de Agosto t\u00eam at\u00e9 hoje, ter\u00e7a-feira, 19 de Mar\u00e7o para conformar as listas no sentido de estarem eleg\u00edveis \u00e0s elei\u00e7\u00f5es do dia 30 de Mar\u00e7o, para o quadri\u00e9nio 2024-2028, segundo o comunicado da Comiss\u00e3o Eleitoral.<\/p>\n<p><span style=\"font-weight: 400;\">A decis\u00e3o decorre da avalia\u00e7\u00e3o feita na \u00faltima sexta-feira(15), na sede do clube militar dos documentos apresentados pelos concorrentes. A CE presidida por Pedro Neto, secret\u00e1rio Paulo Madeira e o escrutinador N\u00b4gouabi Salvador, deu a morat\u00f3ria de setenta e duas horas para cumprirem as exig\u00eancias.937 52 82 74<\/span><\/p>\n<p style=\"font-weight: 400;\">Na presen\u00e7a do candidato Egas Viegas e do mandat\u00e1rio Jos\u00e9 de Ara\u00fajo (Lista A), dos delegados de Gouveia S\u00e1 Miranda, Manuel Katendi, Pedro Calado e Carlos Alonso &#8220;Cali&#8221; (Lista B), do pretendente \u00e0 sua sucess\u00e3o, Carlos Hendrick, acompanhado de Afonso Garrido e Clarisse Gaspar (Lista C), foram informados dos processos em falta.<\/p>\n<p style=\"font-weight: 400;\">O comunicado destaca que &#8220;da verifica\u00e7\u00e3o da conformidade preliminar das listas, constatou existirem inconformidades em todas elas, no entanto, pass\u00edveis de serem ultrapassadas&#8221;.<\/p>\n<p style=\"font-weight: 400;\">Segundo o documento, num esp\u00edrito de isen\u00e7\u00e3o e rigor, mas tamb\u00e9m de cordialidade e compreens\u00e3o m\u00fatua, &#8220;os candidatos, mandat\u00e1rios e comiss\u00e3o eleitoral, acordaram unanimemente, que todas as listas devam conformar-se, dentro dos prazos definidos no Calend\u00e1rio Eleitoral&#8221;.<\/p>\n<p style=\"font-weight: 400;\">A decis\u00e3o relativa \u00e0s reclama\u00e7\u00f5es ser\u00e1 divulgada na pr\u00f3xima quarta-feira, \u00e0s 15h00, na sede do clube. Os candidatos eleg\u00edveis estar\u00e3o autorizados a iniciar a campanha eleitoral do dia 14 a 28, \u00e0s 23h59&#8242;, em todo o pa\u00eds.<\/p>\n<p style=\"font-weight: 400;\">\u00c0s elei\u00e7\u00f5es decorrem no dia 30 do corrente, das 9 \u00e0s 12h00, na Cidade Desportiva, sendo que a publica\u00e7\u00e3o dos resultados oficiais acontece no mesmo dia, tr\u00eas horas depois, ou seja da conclus\u00e3o do escrut\u00ednio. O novo presidente de direc\u00e7\u00e3o toma posse \u00e0s 17h00, do dia 8 de Abril, no CODENM.<\/p>\n<p style=\"font-weight: 400;\">O jurista, Egas Viegas \u00e9 o candidato mais novo, com ideias novas e promete resgatar a m\u00edstica do Clube Central das For\u00e7as Armadas Angolana nas competi\u00e7\u00f5es.<\/p>\n<p style=\"font-weight: 400;\">J\u00e1 o general Gouveia S\u00e1 Miranda surge como a alternativa \u00e0 actual direc\u00e7\u00e3o para voltar a colocar o D&#8217;agosto no lugar que pertence no desporto nacional.<\/p>\n<p style=\"font-weight: 400;\">Por sua vez, o general Carlos Hendrick concorre \u00e0 pr\u00f3pria sucess\u00e3o em busca do quarto mandato para finalizar os projectos iniciados em 2011, ano em que assumiu a direc\u00e7\u00e3o da forma\u00e7\u00e3o militar.<\/p>\n<p>Fonte: Jornal de Angola<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os tr\u00eas candidatos \u00e0 presid\u00eancia do 1\u00ba de Agosto t\u00eam at\u00e9 hoje, ter\u00e7a-feira, 19 de Mar\u00e7o para conformar as listas no sentido de estarem eleg\u00edveis \u00e0s elei\u00e7\u00f5es do dia 30 de Mar\u00e7o, para o quadri\u00e9nio 2024-2028, segundo o comunicado da Comiss\u00e3o Eleitoral. A decis\u00e3o decorre da avalia\u00e7\u00e3o feita na \u00faltima ...<\/p>\n","protected":false},"author":8,"featured_media":135134,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[145,125,164],"tags":[],"_links":{"self":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/135136"}],"collection":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/comments?post=135136"}],"version-history":[{"count":5,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/135136\/revisions"}],"predecessor-version":[{"id":135144,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/135136\/revisions\/135144"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media\/135134"}],"wp:attachment":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media?parent=135136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/categories?post=135136"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/tags?post=135136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}