{"id":124181,"date":"2023-11-30T09:01:08","date_gmt":"2023-11-30T08:01:08","guid":{"rendered":"https:\/\/rna.ao\/rna.ao\/?p=124181"},"modified":"2023-11-30T09:01:08","modified_gmt":"2023-11-30T08:01:08","slug":"distrito-de-ramiros-chuva-pode-cortar-circulacao-entre-luanda-e-as-provincias-do-centro-e-sul-do-pais","status":"publish","type":"post","link":"https:\/\/rna.ao\/rna.ao\/2023\/11\/30\/distrito-de-ramiros-chuva-pode-cortar-circulacao-entre-luanda-e-as-provincias-do-centro-e-sul-do-pais\/","title":{"rendered":"Distrito de Ramiros: Chuva pode cortar circula\u00e7\u00e3o entre Luanda e as Prov\u00edncias do Centro e Sul do pa\u00eds"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"wp-image-119072 alignleft\" src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2023\/10\/Carlos-dos-Santos.jpg\" alt=\"\" width=\"347\" height=\"156\" \/>O Minist\u00e9rio da Constru\u00e7\u00e3o, Obras P\u00fablicas e Urbanismo, vai intervir em vias afectadas pela chuva que cai nos \u00faltimos dias com muita intensidade. A informa\u00e7\u00e3o foi avan\u00e7ada pelo Ministro de tutela, Carlos Alberto dos Santos. Luanda, Bengo, U\u00edge, Zaire, Cuanza-Norte e Cuanza-Sul s\u00e3o as prov\u00edncias que requerem uma maior aten\u00e7\u00e3o.\u00a0Clique, no \u00e1udio abaixo, e ou\u00e7a:<\/p>\n\t<div class=\"qtmplayer-playlist-large\">\n\t\t<ul class=\"qtmplayer-playlist\">\n\t\t\t\n\t\t\t\t\t<li class=\"qtmplayer-trackitem\">\n\t\t<img src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2023\/11\/ESTRADA-100x100.jpg\" alt=\"cover\">\t\t<span \t\t\tdata-qtmplayer-cover=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2023\/11\/ESTRADA.jpg\"\n\t\t\t\t\t\tdata-qtmplayer-file=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2023\/11\/CARLOS-ALBERTO-DOS-SANTOS-1-13-HRS.mp3\"\n\t\t\t\t\t\tdata-qtmplayer-title=\"Distrito de Ramiros: Chuva pode cortar circula\u00e7\u00e3o entre Luanda e as Prov\u00edncias do Centro e Sul do pa\u00eds\"\n\t\t\t\t\t\tdata-qtmplayer-artist=\"RNA\"\n\t\t\t\t\t\tdata-qtmplayer-link=\"https:\/\/rna.ao\/rna.ao\/2023\/11\/30\/distrito-de-ramiros-chuva-pode-cortar-circulacao-entre-luanda-e-as-provincias-do-centro-e-sul-do-pais\/\"\n\t\t\t\t\t\tdata-qtmplayer-icon=\"file_download\"\n\t\t\t\t\t\tdata-qtmplayer-type=\"track\"\n\t\t\t class=\"qtmplayer-play qtmplayer-link-sec qtmplayer-play-btn\"><i class='material-icons'>play_arrow<\/i><\/span>\n\t\t<p>\n\t\t\t<span class=\"qtmplayer-tit\">Distrito de Ramiros: Chuva pode cortar circula\u00e7\u00e3o entre Luanda e as Prov\u00edncias do Centro e Sul do pa\u00eds<\/span>\n\t\t\t<span class=\"qtmplayer-art\">RNA<\/span>\n\t\t<\/p>\n\t<\/li>\n\t\t<\/ul>\n\t<\/div>\t\t\t\n\t\n<p>Carlos Alberto dos Santos disse ainda que nas pr\u00f3ximas semanas o Minist\u00e9rio da constru\u00e7\u00e3o, Obras P\u00fablicas e Urbanismo, vai realizar obras de emerg\u00eancia para conten\u00e7\u00e3o de ravinas no pa\u00eds. O Governante falava depois de constatar tr\u00eas ravinas na estrada nacional 100, sentido Ramiros\/Benfica. Clique, no \u00e1udio abaixo, e ou\u00e7a:<\/p>\n\t<div class=\"qtmplayer-playlist-large\">\n\t\t<ul class=\"qtmplayer-playlist\">\n\t\t\t\n\t\t\t\t\t<li class=\"qtmplayer-trackitem\">\n\t\t<img src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2023\/11\/ESTRADA-100x100.jpg\" alt=\"cover\">\t\t<span \t\t\tdata-qtmplayer-cover=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2023\/11\/ESTRADA.jpg\"\n\t\t\t\t\t\tdata-qtmplayer-file=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2023\/11\/CARLOS-ALBERTO-DOS-SANTOS-2-13-HRS.mp3\"\n\t\t\t\t\t\tdata-qtmplayer-title=\"Distrito de Ramiros: Chuva pode cortar circula\u00e7\u00e3o entre Luanda e as Prov\u00edncias do Centro e Sul do pa\u00eds\"\n\t\t\t\t\t\tdata-qtmplayer-artist=\"RNA\"\n\t\t\t\t\t\tdata-qtmplayer-link=\"https:\/\/rna.ao\/rna.ao\/2023\/11\/30\/distrito-de-ramiros-chuva-pode-cortar-circulacao-entre-luanda-e-as-provincias-do-centro-e-sul-do-pais\/\"\n\t\t\t\t\t\tdata-qtmplayer-icon=\"file_download\"\n\t\t\t\t\t\tdata-qtmplayer-type=\"track\"\n\t\t\t class=\"qtmplayer-play qtmplayer-link-sec qtmplayer-play-btn\"><i class='material-icons'>play_arrow<\/i><\/span>\n\t\t<p>\n\t\t\t<span class=\"qtmplayer-tit\">Distrito de Ramiros: Chuva pode cortar circula\u00e7\u00e3o entre Luanda e as Prov\u00edncias do Centro e Sul do pa\u00eds<\/span>\n\t\t\t<span class=\"qtmplayer-art\">RNA<\/span>\n\t\t<\/p>\n\t<\/li>\n\t\t<\/ul>\n\t<\/div>\t\t\t\n\t\n","protected":false},"excerpt":{"rendered":"<p>O Minist\u00e9rio da Constru\u00e7\u00e3o, Obras P\u00fablicas e Urbanismo, vai intervir em vias afectadas pela chuva que cai nos \u00faltimos dias com muita intensidade. A informa\u00e7\u00e3o foi avan\u00e7ada pelo Ministro de tutela, Carlos Alberto dos Santos. Luanda, Bengo, U\u00edge, Zaire, Cuanza-Norte e Cuanza-Sul s\u00e3o as prov\u00edncias que requerem uma maior aten\u00e7\u00e3o.\u00a0Clique, ...<\/p>\n","protected":false},"author":8,"featured_media":124185,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[141,133],"tags":[],"_links":{"self":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/124181"}],"collection":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/comments?post=124181"}],"version-history":[{"count":1,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/124181\/revisions"}],"predecessor-version":[{"id":124186,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/124181\/revisions\/124186"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media\/124185"}],"wp:attachment":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media?parent=124181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/categories?post=124181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/tags?post=124181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}