{"id":123989,"date":"2023-11-28T10:40:34","date_gmt":"2023-11-28T09:40:34","guid":{"rendered":"https:\/\/rna.ao\/rna.ao\/?p=123989"},"modified":"2023-11-28T10:40:34","modified_gmt":"2023-11-28T09:40:34","slug":"grupo-tecnico-para-o-censo-geral-de-2024-actualiza-malha-cartografica-no-cuanza-norte","status":"publish","type":"post","link":"https:\/\/rna.ao\/rna.ao\/2023\/11\/28\/grupo-tecnico-para-o-censo-geral-de-2024-actualiza-malha-cartografica-no-cuanza-norte\/","title":{"rendered":"Grupo t\u00e9cnico para o censo geral de 2024 actualiza malha cartogr\u00e1fica no Cuanza-Norte"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"size-full wp-image-109934 alignleft\" src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2023\/07\/censo.jpg\" alt=\"\" width=\"259\" height=\"194\" \/>Iniciou esta segunda-feira(27), no Cuanza-Norte, a actualiza\u00e7\u00e3o da malha cartogr\u00e1fica da prov\u00edncia, visando o Censo Geral da Popula\u00e7\u00e3o e Habita\u00e7\u00e3o, que o pa\u00eds realiza em 2024. Nesta primeira fase, a actividade inscreve, tr\u00eas munic\u00edpios; Bolongongo, Quiculungo e Banga. Clique, no \u00e1udio abaixo, e saiba mais com o jornalista Sebasti\u00e3o Serafim:<\/p>\n\t<div class=\"qtmplayer-playlist-large\">\n\t\t<ul class=\"qtmplayer-playlist\">\n\t\t\t\n\t\t\t\t\t<li class=\"qtmplayer-trackitem\">\n\t\t<img src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2023\/10\/censo-populacional-e-habitacao-100x100.jpg\" alt=\"cover\">\t\t<span \t\t\tdata-qtmplayer-cover=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2023\/10\/censo-populacional-e-habitacao.jpg\"\n\t\t\t\t\t\tdata-qtmplayer-file=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2023\/11\/CUANZA-NORTE-CENSO-GERAL-06HRS.mp3\"\n\t\t\t\t\t\tdata-qtmplayer-title=\"Grupo t\u00e9cnico para o censo geral de 2024 actualiza malha cartogr\u00e1fica no Cuanza-Norte\"\n\t\t\t\t\t\tdata-qtmplayer-artist=\"RNA\"\n\t\t\t\t\t\tdata-qtmplayer-link=\"https:\/\/rna.ao\/rna.ao\/2023\/11\/28\/grupo-tecnico-para-o-censo-geral-de-2024-actualiza-malha-cartografica-no-cuanza-norte\/\"\n\t\t\t\t\t\tdata-qtmplayer-icon=\"file_download\"\n\t\t\t\t\t\tdata-qtmplayer-type=\"track\"\n\t\t\t class=\"qtmplayer-play qtmplayer-link-sec qtmplayer-play-btn\"><i class='material-icons'>play_arrow<\/i><\/span>\n\t\t<p>\n\t\t\t<span class=\"qtmplayer-tit\">Grupo t\u00e9cnico para o censo geral de 2024 actualiza malha cartogr\u00e1fica no Cuanza-Norte<\/span>\n\t\t\t<span class=\"qtmplayer-art\">RNA<\/span>\n\t\t<\/p>\n\t<\/li>\n\t\t<\/ul>\n\t<\/div>\t\t\t\n\t\n","protected":false},"excerpt":{"rendered":"<p>Iniciou esta segunda-feira(27), no Cuanza-Norte, a actualiza\u00e7\u00e3o da malha cartogr\u00e1fica da prov\u00edncia, visando o Censo Geral da Popula\u00e7\u00e3o e Habita\u00e7\u00e3o, que o pa\u00eds realiza em 2024. Nesta primeira fase, a actividade inscreve, tr\u00eas munic\u00edpios; Bolongongo, Quiculungo e Banga. Clique, no \u00e1udio abaixo, e saiba mais com o jornalista Sebasti\u00e3o Serafim:<\/p>\n","protected":false},"author":8,"featured_media":120140,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[142,121,163],"tags":[],"_links":{"self":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/123989"}],"collection":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/comments?post=123989"}],"version-history":[{"count":1,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/123989\/revisions"}],"predecessor-version":[{"id":123991,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/123989\/revisions\/123991"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media\/120140"}],"wp:attachment":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media?parent=123989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/categories?post=123989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/tags?post=123989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}