{"id":123959,"date":"2023-11-28T09:35:55","date_gmt":"2023-11-28T08:35:55","guid":{"rendered":"https:\/\/rna.ao\/rna.ao\/?p=123959"},"modified":"2023-11-28T09:35:55","modified_gmt":"2023-11-28T08:35:55","slug":"angola-precisa-eleger-as-melhores-areas-de-cooperacao-com-os-eua-pedro-godinho-presidente-da-camara-de-comercio-angola-e-eua","status":"publish","type":"post","link":"https:\/\/rna.ao\/rna.ao\/2023\/11\/28\/angola-precisa-eleger-as-melhores-areas-de-cooperacao-com-os-eua-pedro-godinho-presidente-da-camara-de-comercio-angola-e-eua\/","title":{"rendered":"&#8220;Angola precisa eleger as melhores \u00e1reas de coopera\u00e7\u00e3o com os EUA&#8221; Pedro Godinho, Presidente da C\u00e2mara de Com\u00e9rcio Angola e EUA"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"wp-image-123962 alignleft\" src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2023\/11\/ng1086949.jpg\" alt=\"\" width=\"392\" height=\"261\" \/>Os Presidentes de Angola, Jo\u00e3o Louren\u00e7o e dos EUA, Joe Biden, v\u00e3o encontrar-se na pr\u00f3xima quinta-feira, 30 de Novembro, na Casa Branca. O encontro entre os dois estadistas enquadra-se nos 30 anos de rela\u00e7\u00f5es entre Angola e os EUA, e vai privilegiar a coopera\u00e7\u00e3o bilateral nos do com\u00e9rcio, investimento, clima e energia, e em particular o desenvolvimento do corredor do Lobito. O encontro de quinta-feira entre os Presidentes Jo\u00e3o Louren\u00e7o e Joe Biden confirma o interesse dos dois pa\u00edses de trabalhar em parceria estrat\u00e9gica para lidar com os desafios regionais e globais. Em entrevista \u00e0 RNA o Presidente da C\u00e2mara de Com\u00e9rcio Angolana, Pedro Godinho, disse que este \u00e9 um momento impar que Angola e defende o melhor aproveitamento de todas as capacidades que os americanos v\u00e3o por a disposi\u00e7\u00e3o do nosso pa\u00eds.<\/p>\n\t<div class=\"qtmplayer-playlist-large\">\n\t\t<ul class=\"qtmplayer-playlist\">\n\t\t\t\n\t\t\t\t\t<li class=\"qtmplayer-trackitem\">\n\t\t<img src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2023\/11\/pedro-godinho-100x100.jpg\" alt=\"cover\">\t\t<span \t\t\tdata-qtmplayer-cover=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2023\/11\/pedro-godinho.jpg\"\n\t\t\t\t\t\tdata-qtmplayer-file=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2023\/11\/ROMAO-FERREIRA-08-HRS.mp3\"\n\t\t\t\t\t\tdata-qtmplayer-title=\"&#8220;Angola precisa eleger as melhores \u00e1reas de coopera\u00e7\u00e3o com os EUA&#8221; Pedro Godinho, Presidente da C\u00e2mara de Com\u00e9rcio Angola e EUA\"\n\t\t\t\t\t\tdata-qtmplayer-artist=\"RNA\"\n\t\t\t\t\t\tdata-qtmplayer-link=\"https:\/\/rna.ao\/rna.ao\/2023\/11\/28\/angola-precisa-eleger-as-melhores-areas-de-cooperacao-com-os-eua-pedro-godinho-presidente-da-camara-de-comercio-angola-e-eua\/\"\n\t\t\t\t\t\tdata-qtmplayer-icon=\"file_download\"\n\t\t\t\t\t\tdata-qtmplayer-type=\"track\"\n\t\t\t class=\"qtmplayer-play qtmplayer-link-sec qtmplayer-play-btn\"><i class='material-icons'>play_arrow<\/i><\/span>\n\t\t<p>\n\t\t\t<span class=\"qtmplayer-tit\">&#8220;Angola precisa eleger as melhores \u00e1reas de coopera\u00e7\u00e3o com os EUA&#8221; Pedro Godinho, Presidente da C\u00e2mara de Com\u00e9rcio Angola e EUA<\/span>\n\t\t\t<span class=\"qtmplayer-art\">RNA<\/span>\n\t\t<\/p>\n\t<\/li>\n\t\t<\/ul>\n\t<\/div>\t\t\t\n\t\n","protected":false},"excerpt":{"rendered":"<p>Os Presidentes de Angola, Jo\u00e3o Louren\u00e7o e dos EUA, Joe Biden, v\u00e3o encontrar-se na pr\u00f3xima quinta-feira, 30 de Novembro, na Casa Branca. O encontro entre os dois estadistas enquadra-se nos 30 anos de rela\u00e7\u00f5es entre Angola e os EUA, e vai privilegiar a coopera\u00e7\u00e3o bilateral nos do com\u00e9rcio, investimento, clima ...<\/p>\n","protected":false},"author":8,"featured_media":123961,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[142,121,163],"tags":[],"_links":{"self":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/123959"}],"collection":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/comments?post=123959"}],"version-history":[{"count":1,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/123959\/revisions"}],"predecessor-version":[{"id":123963,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/123959\/revisions\/123963"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media\/123961"}],"wp:attachment":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media?parent=123959"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/categories?post=123959"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/tags?post=123959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}