{"id":123916,"date":"2023-11-28T08:20:50","date_gmt":"2023-11-28T07:20:50","guid":{"rendered":"https:\/\/rna.ao\/rna.ao\/?p=123916"},"modified":"2023-11-28T08:20:50","modified_gmt":"2023-11-28T07:20:50","slug":"itel-realiza-3a-edicao-da-semana-da-informatica-e-sistemas-multimedia","status":"publish","type":"post","link":"https:\/\/rna.ao\/rna.ao\/2023\/11\/28\/itel-realiza-3a-edicao-da-semana-da-informatica-e-sistemas-multimedia\/","title":{"rendered":"ITEL  realiza 3\u00aa edi\u00e7\u00e3o da Semana da Inform\u00e1tica e Sistemas Multim\u00e9dia"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"wp-image-62170 alignleft\" src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2022\/05\/fititel_363207_20210519170017-770x400.jpg\" alt=\"\" width=\"379\" height=\"197\" srcset=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2022\/05\/fititel_363207_20210519170017-770x400.jpg 770w, https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2022\/05\/fititel_363207_20210519170017-768x399.jpg 768w, https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2022\/05\/fititel_363207_20210519170017.jpg 900w\" sizes=\"(max-width: 379px) 100vw, 379px\" \/>A terceira edi\u00e7\u00e3o da Semana do curso de Inform\u00e1tica e Sistemas Multim\u00e9dia do Instituto de Telecomunica\u00e7\u00f5es-ITEL em Luanda, arrancou na segunda-feira(27) ,e vai at\u00e9 a pr\u00f3xima quarta-feira. O evento dirigido a estudantes do d\u00e9cimo terceiro ano, visa mostrar as val\u00eancias do curso e as iniciativas destes mesmos estudantes, segundo o professor Divangamuene Luyeye.\u00a0Clique no \u00e1udio e ou\u00e7a:<\/p>\n\t<div class=\"qtmplayer-playlist-large\">\n\t\t<ul class=\"qtmplayer-playlist\">\n\t\t\t\n\t\t\t\t\t<li class=\"qtmplayer-trackitem\">\n\t\t<img src=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2022\/05\/fititel_363207_20210519170017-100x100.jpg\" alt=\"cover\">\t\t<span \t\t\tdata-qtmplayer-cover=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2022\/05\/fititel_363207_20210519170017-370x370.jpg\"\n\t\t\t\t\t\tdata-qtmplayer-file=\"https:\/\/rna.ao\/rna.ao\/wp-content\/uploads\/2023\/11\/DIVANGANENO-LUYEYE-1.mp3\"\n\t\t\t\t\t\tdata-qtmplayer-title=\"ITEL  realiza 3\u00aa edi\u00e7\u00e3o da Semana da Inform\u00e1tica e Sistemas Multim\u00e9dia\"\n\t\t\t\t\t\tdata-qtmplayer-artist=\"RNA\"\n\t\t\t\t\t\tdata-qtmplayer-link=\"https:\/\/rna.ao\/rna.ao\/2023\/11\/28\/itel-realiza-3a-edicao-da-semana-da-informatica-e-sistemas-multimedia\/\"\n\t\t\t\t\t\tdata-qtmplayer-icon=\"file_download\"\n\t\t\t\t\t\tdata-qtmplayer-type=\"track\"\n\t\t\t class=\"qtmplayer-play qtmplayer-link-sec qtmplayer-play-btn\"><i class='material-icons'>play_arrow<\/i><\/span>\n\t\t<p>\n\t\t\t<span class=\"qtmplayer-tit\">ITEL  realiza 3\u00aa edi\u00e7\u00e3o da Semana da Inform\u00e1tica e Sistemas Multim\u00e9dia<\/span>\n\t\t\t<span class=\"qtmplayer-art\">RNA<\/span>\n\t\t<\/p>\n\t<\/li>\n\t\t<\/ul>\n\t<\/div>\t\t\t\n\t\n<p>Quanto as iniciativas dos estudantes, o ITEL, tem procurado acompanhar e divulgar. Clique no \u00e1udio e ou\u00e7a:<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A terceira edi\u00e7\u00e3o da Semana do curso de Inform\u00e1tica e Sistemas Multim\u00e9dia do Instituto de Telecomunica\u00e7\u00f5es-ITEL em Luanda, arrancou na segunda-feira(27) ,e vai at\u00e9 a pr\u00f3xima quarta-feira. O evento dirigido a estudantes do d\u00e9cimo terceiro ano, visa mostrar as val\u00eancias do curso e as iniciativas destes mesmos estudantes, segundo o ...<\/p>\n","protected":false},"author":8,"featured_media":62170,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[141,133],"tags":[],"_links":{"self":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/123916"}],"collection":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/comments?post=123916"}],"version-history":[{"count":1,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/123916\/revisions"}],"predecessor-version":[{"id":123918,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/posts\/123916\/revisions\/123918"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media\/62170"}],"wp:attachment":[{"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/media?parent=123916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/categories?post=123916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rna.ao\/rna.ao\/wp-json\/wp\/v2\/tags?post=123916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}